{"id":90756,"date":"2026-07-15T14:15:46","date_gmt":"2026-07-15T17:15:46","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/15\/la-produccion-industrial-de-la-zona-euro-cayo-02-en-mayo-peor-que-lo-esperado\/"},"modified":"2026-07-15T14:15:46","modified_gmt":"2026-07-15T17:15:46","slug":"la-produccion-industrial-de-la-zona-euro-cayo-02-en-mayo-peor-que-lo-esperado","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/15\/la-produccion-industrial-de-la-zona-euro-cayo-02-en-mayo-peor-que-lo-esperado\/","title":{"rendered":"La producci\u00f3n industrial de la zona euro cay\u00f3 0,2% en mayo, peor que lo esperado"},"content":{"rendered":"<p>\t\t                                    \t\t La ca\u00edda fue impulsada por bienes de consumo duraderos y bienes intermedios, contrastando con el alza en energ\u00eda. El detalle por pa\u00edses, en la nota. <\/p>\n<p>\t\t      \t\t\t\t\t\t \t\t\t\t\t\t\t\tEuro hoy y Euro blue hoy: a cu\u00e1nto cotiza este mi\u00e9rcoles 15 de julio \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\tEuro hoy y Euro blue hoy: a cu\u00e1nto cotiz\u00f3 este martes 14 de julio \t\t\t\t\t\t\t\t\t \t          Producci\u00f3n industrial: Retrocedi\u00f3 un 0,2% en mayo en la zona euro, por debajo de las expectativas de los analistas.<\/p>\n<p>           La producci\u00f3n industrial de la zona euro registr\u00f3 una contracci\u00f3n del 0,2% en mayo en comparaci\u00f3n con el mes anterior (en t\u00e9rminos ajustados por estacionalidad), seg\u00fan los datos oficiales publicados por Eurostat, la oficina de estad\u00edsticas de la Uni\u00f3n Europea.<\/p>\n<p>         De esta manera, la cifra representa una decepci\u00f3n para los analistas de mercado, quienes esperaban un dato m\u00e1s alentador cercano a un incremento del 0,2% para el quinto mes del a\u00f1o. Adem\u00e1s, Eurostat revis\u00f3 al alza el dato de abril, que pas\u00f3 de una estimaci\u00f3n inicial del 0,1% a un 0,3% de incremento.<\/p>\n<p>         \t     Si ampliamos el an\u00e1lisis al conjunto de la Uni\u00f3n Europea (UE), la producci\u00f3n industrial experiment\u00f3 un descenso ligeramente menor, situ\u00e1ndose en el -0,1% intermensual.<\/p>\n<p>       El detalle por sectores industriales La ca\u00edda mensual en la zona euro estuvo motorizada por los bienes de consumo duraderos y los bienes intermedios, un comportamiento que contrasta con el aumento en el sector energ\u00e9tico. <\/p>\n<p>         Los bienes de consumo duraderos: Cayeron un 1,1% en la zona euro.<\/p>\n<p>   Bienes intermedios: Retrocedieron un 0,3%.<\/p>\n<p>   Bienes de capital: Registraron un leve repunte del 0,3%.<\/p>\n<p>   Bienes de consumo no duraderos: Subieron un 0,8%.<\/p>\n<p>   Energ\u00eda: Fue el sector con mayor impulso, escalando un 2,2% en la zona euro.<\/p>\n<p>     El desglose por pa\u00eds  El panorama de la actividad fabril en Europa es heterog\u00e9neo y asim\u00e9trico, con fuertes distorsiones originadas principalmente en la volatilidad del sector manufacturero y tecnol\u00f3gico irland\u00e9s.<\/p>\n<p>       Mayores ca\u00eddas mensuales (respecto a abril de 2026):<\/p>\n<p>    Irlanda: -5,2%<\/p>\n<p>    Malta: -3,7%<\/p>\n<p>    Lituania: -3,0%<\/p>\n<p>     Mayores incrementos mensuales (respecto a abril de 2026):<\/p>\n<p>    Luxemburgo: +2,7%<\/p>\n<p>    Hungr\u00eda: +2,3%<\/p>\n<p>    Polonia: +2,0%<\/p>\n<p>     Por su parte, Las ca\u00eddas interanuales m\u00e1s pronunciadas se registraron en Irlanda (-19,7%), Bulgaria (-4,7%) y Estonia (-3,0%). <\/p>\n<p>  Mientras que En el extremo opuesto, los crecimientos m\u00e1s s\u00f3lidos en la comparaci\u00f3n interanual correspondieron a Dinamarca y Suecia (+6,5%), Letonia (+6,2%) y Hungr\u00eda (+5,4%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ca\u00edda fue impulsada por bienes de consumo duraderos y bienes intermedios, contrastando con el alza en energ\u00eda. El detalle por pa\u00edses, en la nota. Euro hoy y Euro blue hoy: a cu\u00e1nto cotiza este mi\u00e9rcoles 15 de julio Euro hoy y Euro blue hoy: a cu\u00e1nto cotiz\u00f3 este martes 14 de julio Producci\u00f3n industrial: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,42],"tags":[],"class_list":["post-90756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","category-economics"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90756"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90757"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}