{"id":90456,"date":"2026-07-15T01:25:54","date_gmt":"2026-07-15T04:25:54","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/15\/kwame-nkrumah-padre-del-panafricanismo-e-ideologo-olvidado-de-conakry\/"},"modified":"2026-07-15T01:25:54","modified_gmt":"2026-07-15T04:25:54","slug":"kwame-nkrumah-padre-del-panafricanismo-e-ideologo-olvidado-de-conakry","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/15\/kwame-nkrumah-padre-del-panafricanismo-e-ideologo-olvidado-de-conakry\/","title":{"rendered":"Kwame N&#8217;Krumah, padre del panafricanismo e ide\u00f3logo olvidado de Conakry"},"content":{"rendered":"<p>                   Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot).                                    Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr             Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID).         <\/p>\n<p>                              Su tr\u00e1fico ha sido identificado como automatizado (actividad de bot).<\/p>\n<p>                                    Si es un socio autorizado, un suscriptor de Le Monde o si desea solicitar permiso para acceder a este contenido, comun\u00edquese con: licencia[@]grupoelemonde.fr             e incluya una copia de esta p\u00e1gina de error que muestre su direcci\u00f3n IP y su ID de solicitud (RID).         <\/p>\n<p>                    IP: 74.208.218.121<br \/>\nDESHACERSE: 71aac04fe4204360810d000000000001<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot). Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID). Su tr\u00e1fico ha sido identificado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23209,59],"tags":[],"class_list":["post-90456","post","type-post","status-publish","format-standard","has-post-thumbnail","category-kwame","category-politics"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90456"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90456\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90457"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}