{"id":90430,"date":"2026-07-14T23:16:46","date_gmt":"2026-07-15T02:16:46","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/dolar-ya-se-conoce-el-techo-de-la-banda-para-fines-de-agosto-hasta-donde-puede-subir\/"},"modified":"2026-07-14T23:16:46","modified_gmt":"2026-07-15T02:16:46","slug":"dolar-ya-se-conoce-el-techo-de-la-banda-para-fines-de-agosto-hasta-donde-puede-subir","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/dolar-ya-se-conoce-el-techo-de-la-banda-para-fines-de-agosto-hasta-donde-puede-subir\/","title":{"rendered":"D\u00f3lar: ya se conoce el techo de la banda para fines de agosto, \u00bfhasta d\u00f3nde puede subir?"},"content":{"rendered":"<p>\t\t                                    \t\t El IPC de junio fue de 1,9% y defini\u00f3 el pr\u00f3ximo ajuste del esquema cambiario. As\u00ed, la referencia llegar\u00e1 se acerc\u00f3 a los $1.900 para el \u00faltimo d\u00eda h\u00e1bil de agosto, mientras el REM mantiene al mayorista por debajo de esa marca.<\/p>\n<p>\t\t      \t\t\t\t\t\t \t\t\t\t\t\t\t\tWall Street cerr\u00f3 al alza tras el buen dato de inflaci\u00f3n en EEUU y con el foco en los resultados bancarios \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t \t\t\t\t\t\t\t\tPlazo fijo: cu\u00e1nto se obtiene al invertir $250.000 \t\t\t\t\t\t\t\t\t \t         La actualizaci\u00f3n diaria llevar\u00e1 el l\u00edmite superior desde $1.844,87 a fines de julio hasta $1.879,92 durante agosto.<\/p>\n<p>          La inflaci\u00f3n  fue de 1,9% en junio, acumul\u00f3 16,8% en el primer semestre y alcanz\u00f3 una variaci\u00f3n interanual de 33,5%. Con ese dato, el techo de la banda cambiaria subir\u00e1 durante agosto desde los $1.844,87 previstos para el cierre de julio hasta $1.879,92 el \u00faltimo d\u00eda h\u00e1bil del mes.<\/p>\n<p>         Mientras tanto, el l\u00edmite superior continuar\u00e1 avanzando durante las ruedas que restan de julio. Este martes 14 se ubica en $1.823,96 y llegar\u00e1 a $1.844,87 el viernes 31, seg\u00fan el cronograma del Banco Central. En paralelo, tomando el cierre del lunes, el d\u00f3lar mayorista se ubic\u00f3 en $1.486,05, por lo que cuenta con un margen de casi 23% hasta el techo vigente.<\/p>\n<p>         \t     A su vez, el IPC de junio volvi\u00f3 a ubicarse por debajo del 2%. Mientras la inflaci\u00f3n n\u00facleo fue de 1,6%, los precios estacionales subieron 3,4% y los regulados avanzaron 2,3%.<\/p>\n<p>       C\u00f3mo funciona la banda y qu\u00e9 implica para el BCRA Desde enero de 2026, el piso y el techo dejaron de moverse a una tasa fija de 1% mensual y comenzaron a actualizarse seg\u00fan la inflaci\u00f3n publicada por el INDEC con dos meses de rezago. Por lo tanto, el IPC de junio determina el recorrido de agosto, mientras que el dato de julio definir\u00e1 el ajuste de septiembre.<\/p>\n<p>       Adem\u00e1s, la variaci\u00f3n mensual no se aplica de una sola vez, sino que se distribuye de forma diaria hasta completar el porcentaje correspondiente al cierre de cada mes. Dentro de ese esquema, el d\u00f3lar puede fluctuar entre ambos l\u00edmites y, si alcanza el techo, el BCRA debe vender divisas para sostenerlo. Por eso, la suba del l\u00edmite superior eleva el nivel a partir del cual la autoridad monetaria tendr\u00eda que utilizar reservas, mientras mantiene margen para comprar d\u00f3lares dentro de la banda.<\/p>\n<p>       A la vez, el Central acumul\u00f3 m\u00e1s de u$s11.400 millones de compras durante 2026 y super\u00f3 las 120 ruedas consecutivas con saldo comprador. Sin embargo, las reservas brutas rondan los u$s48.000 millones, debido a que tambi\u00e9n reciben el impacto de pagos de deuda, movimientos de encajes y variaciones de valuaci\u00f3n.<\/p>\n<p> Qu\u00e9 proyecta el REM para los pr\u00f3ximos meses Para julio, el \u00faltimo REM estim\u00f3 una inflaci\u00f3n de 2%, mientras que proyect\u00f3 1,8% tanto para agosto como para septiembre. Si esas previsiones se cumplen, el techo de la banda subir\u00eda a $1.917,52 a fines de septiembre, avanzar\u00eda hasta $1.952,04 en octubre y llegar\u00eda a $1.987,18 en noviembre.<\/p>\n<p>  De todos modos, esos valores no est\u00e1n confirmados, porque cada actualizaci\u00f3n depender\u00e1 del dato que publique el INDEC dos meses antes. As\u00ed, la trayectoria podr\u00e1 modificarse si la inflaci\u00f3n mensual se aparta de las estimaciones relevadas por el BCRA.<\/p>\n<p> En paralelo, el REM prev\u00e9 un d\u00f3lar mayorista promedio de $1.482 en julio, $1.513 en agosto, $1.548 en septiembre, $1.589 en octubre y $1.621 en noviembre. Por lo tanto, las proyecciones mantienen al tipo de cambio por debajo del techo durante todo el per\u00edodo. Incluso para diciembre, cuando la mediana espera un d\u00f3lar de $1.673, la referencia seguir\u00eda lejos del l\u00edmite superior si la inflaci\u00f3n avanza en l\u00ednea con las estimaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El IPC de junio fue de 1,9% y defini\u00f3 el pr\u00f3ximo ajuste del esquema cambiario. As\u00ed, la referencia llegar\u00e1 se acerc\u00f3 a los $1.900 para el \u00faltimo d\u00eda h\u00e1bil de agosto, mientras el REM mantiene al mayorista por debajo de esa marca. Wall Street cerr\u00f3 al alza tras el buen dato de inflaci\u00f3n en EEUU [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,42],"tags":[],"class_list":["post-90430","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","category-economics"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90430"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90431"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}