{"id":90414,"date":"2026-07-14T22:38:54","date_gmt":"2026-07-15T01:38:54","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/gobernadores-y-gremios-de-la-region-caribe-cierran-filas-con-ministra-de-minas-y-energia-designada-y-le-entregan-plan-para-enfrentar-crisis-electrica\/"},"modified":"2026-07-14T22:38:54","modified_gmt":"2026-07-15T01:38:54","slug":"gobernadores-y-gremios-de-la-region-caribe-cierran-filas-con-ministra-de-minas-y-energia-designada-y-le-entregan-plan-para-enfrentar-crisis-electrica","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/gobernadores-y-gremios-de-la-region-caribe-cierran-filas-con-ministra-de-minas-y-energia-designada-y-le-entregan-plan-para-enfrentar-crisis-electrica\/","title":{"rendered":"Gobernadores y gremios de la regi\u00f3n Caribe cierran filas con ministra de Minas y Energ\u00eda designada y le entregan plan para enfrentar crisis el\u00e9ctrica"},"content":{"rendered":"<p>Noticia<\/p>\n<p>Dentro de las primeras solicitudes dirigidas a Arboleda Arango aparece la necesidad de garantizar recursos para la operaci\u00f3n de Air-e Intervenida.<\/p>\n<p>El punto de partida fue el respaldo expresado por la Regi\u00f3n Administrativa y de Planificaci\u00f3n (RAP) Caribe.  Foto: Gobernaci\u00f3n del Atl\u00e1ntico<\/p>\n<p>14.07.2026 17:15 Actualizado: 14.07.2026 17:15 <\/p>\n<p>       La crisis energ\u00e9tica que desde hace meses viene encendiendo las alarmas en la regi\u00f3n Caribe volvi\u00f3 a ubicarse en el centro de la agenda nacional. <\/p>\n<p>  LEA TAMBI\u00c9N <\/p>\n<p>Esta vez, el punto de partida fue el respaldo expresado por la Regi\u00f3n Administrativa y de Planificaci\u00f3n (RAP) Caribe y los principales gremios empresariales de la regi\u00f3n a la designaci\u00f3n de Mar\u00eda Nohem\u00ed Arboleda Arango como nuevo Ministerio de Minas y Energ\u00eda del gobierno del presidente electo Abelardo de la Espriella..<\/p>\n<p>A trav\u00e9s de un pronunciamiento conjunto, los integrantes de la Mesa Energ\u00e9tica del Caribe destacaron la trayectoria t\u00e9cnica de la funcionaria designada, especialmente por su paso por xmoperador encargado de la administraci\u00f3n del mercado electrico colombianoy manifestaron su disposici\u00f3n para trabajar de manera articulada en la b\u00fasqueda de soluciones a los problemas que enfrenta el sector.<\/p>\n<p>Apenas un mes atr\u00e1s, gobernadores de la regi\u00f3n, congresistas, empresarios y representantes del sector energ\u00e9tico hab\u00edan advertido desde Monter\u00eda sobre los riesgos riesgos que enfrenta el sistema electrico del caribeal considerar que la situaci\u00f3n ya no puede entenderse como una problem\u00e1tica exclusivamente regional, sino como un asunto de inter\u00e9s nacional.<\/p>\n<p>Mar\u00eda Nohem\u00ed Arboleda Arango, nueva ministra de Minas y Energ\u00eda.  Foto:Archivo Particular.<\/p>\n<p>En aquella oportunidad, los mandatarios departamentales suscribieron la denominada \u201cDeclaraci\u00f3n de Monter\u00eda\u201d, un documento en el que pidieron al pr\u00f3ximo Gobierno Nacional adoptar medidas urgentes frente a lo que calificaron como una combinaci\u00f3n de factores cr\u00edticos: riesgo de desabastecimiento, vulnerabilidad operativa del sistema, tarifas superiores al promedio nacional, dificultades financieras de las empresas prestadoras del servicio y retrasos en proyectos estrat\u00e9gicos para la expansi\u00f3n energ\u00e9tica.<\/p>\n<p>Ahora, con la llegada de una nueva ministra al sector, los l\u00edderes del caribe buscan convertir ese diagn\u00f3stico en una hoja de ruta de trabajo.<\/p>\n<p>Las prioridades sobre la mesaDentro de las primeras solicitudes dirigidas a ArboledaArango aparece la necesidad de garantizar recursos para la operaci\u00f3n de Air-e Intervenida.<\/p>\n<p>La crisis energ\u00e9tica desde hace meses viene encendiendo las alarmas en la regi\u00f3n Caribe.  Foto:Archivo\/EL TIEMPO<\/p>\n<p>Los gremios plantearon que el Gobierno debe asegurar la capitalizaci\u00f3n de la compa\u00f1\u00eda a trav\u00e9s del Fondo Empresarial de la Superintendencia de Servicios P\u00fablicosas\u00ed como encontrar mecanismos que permitan cubrir las obligaciones que mantiene con generadores, transmisores y dem\u00e1s agentes del mercado, una deuda que supera los $2,7 billones.<\/p>\n<p>El prop\u00f3sito, seg\u00fan el documento, es mantener la continuidad del servicio mientras se define un nuevo operador para la empresa.<\/p>\n<p>A ello se suma la preocupaci\u00f3n por la situaci\u00f3n financiera de Afiniacomercializadora que opera en varios departamentos de la regi\u00f3n Caribe y que, seg\u00fan los gremios, enfrenta dificultades asociadas a elevadas perdidas de energiabajos niveles de recaudo, fraude en el servicio y una demanda creciente en una zona con altos niveles de vulnerabilidad social.<\/p>\n<p>Los representantes empresariales consideran que estas condiciones exigen medidas diferenciadas frente al resto del pa\u00eds.<\/p>\n<p>Por tal raz\u00f3n, uno de los planteamientos m\u00e1s relevantes consiste en dise\u00f1ar un nuevo modelo de gesti\u00f3n para el sistema electrico regionalcuya estructura reconoce las particularidades de los distintos mercados del caribe.<\/p>\n<p>La propuesta plantea que no es posible aplicar una misma f\u00f3rmula para atender grandes centros urbanos, barrios subnormales y zonas rurales dispersasdebido a las diferencias sociales, econ\u00f3micas y operativas que existen entre esos sectores.<\/p>\n<p>El Caribe, eje de la transici\u00f3n energ\u00e9ticael respaldo a la nueva ministra Estuvo tambi\u00e9n acompa\u00f1ado por una insistencia en acelerar proyectos que desde hace a\u00f1os aparecen como estrat\u00e9gicos para la regi\u00f3n.<\/p>\n<p>El d\u00eda de la &#8216;Declaraci\u00f3n de Monter\u00eda&#8217;.  Foto:cortesia<\/p>\n<p>En concreto, los gremios solicitaron destrabar la ejecuci\u00f3n de iniciativas solares y e\u00f3licas mediante la agilizaci\u00f3n de tr\u00e1mites regulatoriosel fortalecimiento de la infraestructura de transmisionla mejora en los procesos de conexion a las redes y la consolidaci\u00f3n de acuerdos con las comunidades donde se desarrollar\u00e1n estos proyectos.<\/p>\n<p>La petici\u00f3n coincide con uno de los diagnostico que los gobernadores expusieron en junio durante la cumbre energ\u00e9tica realizada en Monter\u00eda.<\/p>\n<p>En ese encuentro se advirti\u00f3 que m\u00e1s de 120 proyectos energ\u00e9ticos permanec\u00edan frenado en distintas etapas de tr\u00e1mite, retrasando la expansi\u00f3n del sistema y limitando la capacidad de respuesta frente al crecimiento de la demanda.<\/p>\n<p>Precisamente, uno de los argumentos reiterados por los l\u00edderes regionales es que el Caribe no solo concentrate en una demanda creciente de energ\u00edasino que adem\u00e1s posee condiciones estrat\u00e9gicas para convertirse en uno de los principales polos de generaci\u00f3n renovable del pa\u00eds.<\/p>\n<p>  LEA TAMBI\u00c9N <\/p>\n<p>Por ello, los gremios plantearon que el nuevo gobierno impulso una pol\u00edtico que consolidar a la regi\u00f3n como el principal hub energ\u00e9tico de colombiaaprovechando no solo el potencial solar y e\u00f3licosino tambi\u00e9n los recursos asociados a hidrocarburos costa afuera y minerales estrat\u00e9gicos como carb\u00f3n, n\u00edquel y cobre.<\/p>\n<p>Tambi\u00e9n te podr\u00eda interesar:<\/p>\n<p>#ElTiempo #\u00daltimaHora #Cuba #EstadosUnidos #EEUU  Foto:EL TIEMPO<\/p>\n<p>  Sigue toda la informaci\u00f3n de Colombia en Facebook y Twitter, o en nuestro bolet\u00edn semanal. <\/p>\n<p>BOLETINES EL TIEMPO<\/p>\n<p>Reg\u00edstrate en nuestros boletines y recibe noticias en tu correo seg\u00fan tus intereses. Mantente informado con lo que realmente te importa.<\/p>\n<p>NOTICIAS DE GOOGLE EL TIEMPO<\/p>\n<p>S\u00edguenos en GOOGLE NEWS. Mantente siempre actualizado con las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en Google News.<\/p>\n<p>EL TIEMPO WHATSAPP<\/p>\n<p>\u00danete al canal de El Tiempo en WhatsApp para estar al d\u00eda con las noticias m\u00e1s relevantes al momento.<\/p>\n<p>APLICACI\u00d3N EL TIEMPO<\/p>\n<p>Mantente informado con la app de EL TIEMPO. Recibe las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en tu dispositivo.<\/p>\n<p>SUSCR\u00cdBETE AL DIGITAL<\/p>\n<p>Informaci\u00f3n confiable para ti. Suscr\u00edbete a EL TIEMPO y consulta de forma ilimitada nuestros contenidos period\u00edsticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticia Dentro de las primeras solicitudes dirigidas a Arboleda Arango aparece la necesidad de garantizar recursos para la operaci\u00f3n de Air-e Intervenida. El punto de partida fue el respaldo expresado por la Regi\u00f3n Administrativa y de Planificaci\u00f3n (RAP) Caribe. Foto: Gobernaci\u00f3n del Atl\u00e1ntico 14.07.2026 17:15 Actualizado: 14.07.2026 17:15 La crisis energ\u00e9tica que desde hace meses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[768,585],"tags":[],"class_list":["post-90414","post","type-post","status-publish","format-standard","has-post-thumbnail","category-barranquilla","category-colombia"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90414"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90415"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}