{"id":90356,"date":"2026-07-14T18:38:06","date_gmt":"2026-07-14T21:38:06","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/muere-martha-lillard-la-ultima-paciente-de-polio-en-ee-uu-que-dependia-de-un-pulmon-de-acero\/"},"modified":"2026-07-14T18:38:06","modified_gmt":"2026-07-14T21:38:06","slug":"muere-martha-lillard-la-ultima-paciente-de-polio-en-ee-uu-que-dependia-de-un-pulmon-de-acero","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/muere-martha-lillard-la-ultima-paciente-de-polio-en-ee-uu-que-dependia-de-un-pulmon-de-acero\/","title":{"rendered":"Muere Martha Lillard, la \u00faltima paciente de polio en EE.UU. que depend\u00eda de un pulm\u00f3n de acero"},"content":{"rendered":"<p>       Martha Lillard, considerada la \u00faltima paciente de poliomielitis en Estados Unidos que utilizaba un pulm\u00f3n de acero para sobrevivir, falleci\u00f3 el pasado 26 de junio en Oklahoma a los 78 a\u00f1os. Su historia se convirti\u00f3 en un s\u00edmbolo de resiliencia tras vivir m\u00e1s de siete d\u00e9cadas con las secuelas de la enfermedad.<\/p>\n<p>    Lillard contrajo polio cuando ten\u00eda cinco a\u00f1os y desde entonces dependi\u00f3 de un pulm\u00f3n de acero, un respirador mec\u00e1nico que ayudaba a expandir y contraer sus pulmones mediante cambios de presi\u00f3n de aire.<\/p>\n<p>    Su hermana menor, Cindy McVey, inform\u00f3 que la causa de su fallecimiento estuvo relacionada con las secuelas del covid-19 prolongado. Seg\u00fan el certificado de defunci\u00f3n, la muerte fue consecuencia de insuficiencia pulmonar cr\u00f3nica y s\u00edndrome pospolio.<\/p>\n<p>    \u00abLe dijeron que no deb\u00eda vivir m\u00e1s all\u00e1 de los 20 a\u00f1os, pero ten\u00eda el entusiasmo y la determinaci\u00f3n para sacar el m\u00e1ximo provecho de su vida\u00bb, record\u00f3 McVey.<\/p>\n<p>    Una vida marcada por la poliomielitis    La poliomielitis la dej\u00f3 paralizada desde el cuello hacia abajo cuando era una ni\u00f1a. Durante su infancia asist\u00eda solo un par de horas al colegio y el resto de sus estudios los realizaba desde casa.<\/p>\n<p>    M\u00e1s adelante curs\u00f3 la secundaria mediante un sistema telef\u00f3nico conectado con las aulas, lo que le permiti\u00f3 continuar su educaci\u00f3n pese a sus limitaciones f\u00edsicas.<\/p>\n<p>    Con el paso de los a\u00f1os recuper\u00f3 parcialmente la movilidad del brazo izquierdo y de las piernas gracias a la rehabilitaci\u00f3n, aunque nunca dej\u00f3 de depender del pulm\u00f3n de acero para dormir y, en sus \u00faltimos a\u00f1os, pr\u00e1cticamente durante todo el d\u00eda.<\/p>\n<p>    Internet le permitio encontrar el amor    A pesar de las dificultades, Martha Lillard llev\u00f3 una vida activa dentro de sus posibilidades.<\/p>\n<p>    Tras los atentados del 11 de septiembre de 2001 comenzaron a participar en foros de internet para conocer m\u00e1s sobre la actualidad. All\u00ed conoci\u00f3 a Baha Salh, un ciudadano egipcio con quien mantuvo una relaci\u00f3n a distancia durante m\u00e1s de dos d\u00e9cadas.<\/p>\n<p>    La pareja logr\u00f3 casarse en febrero de este a\u00f1o, luego de que Salh obtuviera una visa para viajar a Estados Unidos.<\/p>\n<p>    \u00abRealmente eran almas gemelas\u00bb, afirm\u00f3 su hermana.<\/p>\n<p>    Las secuelas del covid agravaron su estado    Durante la pandemia contrajo covid-19 en dos oportunidades, situaci\u00f3n que deterior\u00f3 a\u00fan m\u00e1s su ya reducida capacidad pulmonar.<\/p>\n<p>    Antes de los contagios, sus pulmones funcionaban por debajo del 25% de su capacidad. En los \u00faltimos cinco a\u00f1os de vida dej\u00f3 de salir de casa debido a las dificultades para respirar y durante los dos a\u00f1os finales permanecieron pr\u00e1cticamente las 24 horas dentro del pulm\u00f3n de acero.<\/p>\n<p>    Una mujer creativa y amante de los animales.    Adem\u00e1s de enfrentar las limitaciones impuestas por la enfermedad, Lillard desarroll\u00f3 una faceta art\u00edstica. Escrib\u00eda poemas, compon\u00eda canciones y colaboraba como voluntaria en el rescate de animales, especialmente de perros de raza beagle.<\/p>\n<p>    Incluso redact\u00f3 su propio obituario, en el que dej\u00f3 constancia de su amor por los animales y de las actividades solidarias que realiz\u00f3 durante su vida.<\/p>\n<p>    En los \u00faltimos a\u00f1os, ella y su hermana intentaron encontrar especialistas capaces de reparar el antiguo pulm\u00f3n de acero que utilizaba, una tarea cada vez m\u00e1s dif\u00edcil debido a que ya no exist\u00edan pacientes que dependieran de ese tipo de equipos.<\/p>\n<p>    Con su fallecimiento concluye una etapa de la historia de la medicina en Estados Unidos, marcada por una enfermedad que antes de la llegada de las vacunas provoc\u00f3 miles de casos de par\u00e1lisis infantil y que hoy permanece controlada gracias a la inmunizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martha Lillard, considerada la \u00faltima paciente de poliomielitis en Estados Unidos que utilizaba un pulm\u00f3n de acero para sobrevivir, falleci\u00f3 el pasado 26 de junio en Oklahoma a los 78 a\u00f1os. Su historia se convirti\u00f3 en un s\u00edmbolo de resiliencia tras vivir m\u00e1s de siete d\u00e9cadas con las secuelas de la enfermedad. Lillard contrajo polio [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":90357,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[525,3429],"tags":[],"class_list":["post-90356","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bolivia","category-internacional"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90356"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90357"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}