{"id":90330,"date":"2026-07-14T18:36:44","date_gmt":"2026-07-14T21:36:44","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/jesus-luzardo-habla-sobre-su-participacion-en-el-juego-de-estrellas-es-un-honor\/"},"modified":"2026-07-14T18:36:44","modified_gmt":"2026-07-14T21:36:44","slug":"jesus-luzardo-habla-sobre-su-participacion-en-el-juego-de-estrellas-es-un-honor","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/jesus-luzardo-habla-sobre-su-participacion-en-el-juego-de-estrellas-es-un-honor\/","title":{"rendered":"Jes\u00fas Luzardo habla sobre su participaci\u00f3n en el Juego de Estrellas: \u201cEs un honor\u201d"},"content":{"rendered":"<p>En su primera participaci\u00f3n en el Juego de Estrellas de Grandes Ligas, Jes\u00fas Luzardo sabe que se trata de una experiencia especial. El zurdo, abredor de los Filis de Filadelfia, se sentir\u00e1 en casa, pues el cl\u00e1sico de mitad de temporada se llevar\u00e1 a cabo en el Citizens Bank Park, donde su equipo ejerce como club local.<\/p>\n<p>&#8220;Para m\u00ed es un honor. Yo creo que es una bendici\u00f3n poder estar aqu\u00ed&#8221;, dijo el nacido en Per\u00fa y nacionalizado venezolano a la web oficial de MLB.<\/p>\n<p>\u201cEl contrato que ellos me dieron a m\u00ed, a mi familia, gracias a Dios, y bueno, queremos representar a los Filis de una manera buena, de una forma bien y poder darles por lo menos un espect\u00e1culo a esta gente, a los fan\u00e1ticos\u201d, agreg\u00f3.<\/p>\n<p>M\u00e9ritosEl pasado martes, Luzardo recibi\u00f3 la invitaci\u00f3n a su primer Juego de Estrellas despu\u00e9s de ocho a\u00f1os en las Grandes Ligas. La oportunidad lleg\u00f3 como reemplazo de Max Meyer. Y los n\u00fameros est\u00e1n ah\u00ed: a la fecha tiene marca de 8-4 en 19 aperturas, con efectividad de 3.51 en una actuaci\u00f3n que se extiende por 110.1 entradas.<\/p>\n<p>\u201cDesde chiquito a m\u00ed me gustaba ver los lanzadores que lanzaban muchas entradas\u201d, coment\u00f3. \u201cYo creo que siendo un abredor, uno debe tomar el orgullo en eso, en que puede comer muchas entradas y lanzar y darle una oportunidad a su equipo para ganar en cada salida\u201d.<\/p>\n<p>Aparte de su participaci\u00f3n en el Juego de Estrellas, Jes\u00fas Luzardo aspira a seguir haciendo el trabajo para ayudar a encaminar a los Filis, en primera instancia, a la postemporada.<\/p>\n<p>\u201cBuscar la consistencia entre cada salida, trabajar mucho en la mec\u00e1nica, la mezcla de pitcheos (\u2026) y m\u00e1s consistencia buscando la zona con todos los pitcheos, mont\u00e1ndonos adelante en todos los conteos con cada bateador\u201d, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En su primera participaci\u00f3n en el Juego de Estrellas de Grandes Ligas, Jes\u00fas Luzardo sabe que se trata de una experiencia especial. El zurdo, abredor de los Filis de Filadelfia, se sentir\u00e1 en casa, pues el cl\u00e1sico de mitad de temporada se llevar\u00e1 a cabo en el Citizens Bank Park, donde su equipo ejerce como [&hellip;]<\/p>\n","protected":false},"author":488,"featured_media":90331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2153,2156,11605,3329,332],"tags":[],"class_list":["post-90330","post","type-post","status-publish","format-standard","has-post-thumbnail","category-beisbol","category-grandes-ligas","category-jesus-luzardo","category-mlb","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/488"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90330"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90331"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}