{"id":90272,"date":"2026-07-14T17:16:50","date_gmt":"2026-07-14T20:16:50","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/jorge-nieto-realizo-visita-a-keiko-fujimori-en-su-oficina-de-san-isidro\/"},"modified":"2026-07-14T17:16:50","modified_gmt":"2026-07-14T20:16:50","slug":"jorge-nieto-realizo-visita-a-keiko-fujimori-en-su-oficina-de-san-isidro","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/jorge-nieto-realizo-visita-a-keiko-fujimori-en-su-oficina-de-san-isidro\/","title":{"rendered":"Jorge Nieto realiz\u00f3 visita a Keiko Fujimori en su oficina de San Isidro"},"content":{"rendered":"<p>El excandidato presidencial y l\u00edder del Partido del Buen Gobierno, Jorge Nietolleg\u00f3 a las oficinas de la presidenta electa Keiko Fujimori para saludarla y mantener un di\u00e1logo con ella. <\/p>\n<p>El excandidato presidencial y l\u00edder del Partido del Buen Gobierno, Jorge Nietolleg\u00f3 a las oficinas de la presidenta electa Keiko Fujimori para saludarla y mantener un di\u00e1logo con ella. <\/p>\n<p>Al promediar las 11:00 am de este martes, Nieto lleg\u00f3 a bordo de una camioneta roja, e ingres\u00f3 sin brindar declaraciones. <\/p>\n<p>Se espera que tras la reuni\u00f3n ambos puedan dar un pronunciamiento al respecto. <\/p>\n<p>Al t\u00e9rmino de la reuni\u00f3n, Nieto remarc\u00f3 que su agrupaci\u00f3n no formar\u00e1 parte del pr\u00f3ximo Gobierno y ejercer\u00e1 un rol de oposici\u00f3n. No obstante, asegur\u00f3 que respaldar\u00e1 las iniciativas que consideren beneficiosas para el pa\u00eds.<\/p>\n<p>&#8220;Seremos una oposici\u00f3n leal al Per\u00fa. Se\u00f1alaremos todo aquello que no nos parezca y aprobaremos todo aquello que nos parezca conducente con los peruanos. Sobre la posibilidad de tener miembros en el gabinete, no es nuestra expectativa. Seremos oposici\u00f3n&#8221;.<\/p>\n<p>El excandidato del Partido por el Buen Gobierno, tambi\u00e9n afirm\u00f3 que durante la reuni\u00f3n insisti\u00f3 en la necesidad de reducir la polarizaci\u00f3n pol\u00edtica y promover gestos que contribuyan a la reconciliaci\u00f3n nacional.<\/p>\n<p>&#8220;Creemos que debemos salir de una etapa larga de polarizaci\u00f3n. Necesitamos que el pa\u00eds est\u00e9 cohesionado para salir adelante. Nos viene uno pronto, el Ni\u00f1o Costero. Recuerdo que en un momento de nuestra historia fuimos una sola fuerza, y en relaci\u00f3n con ese tema debemos estar cohesionados&#8221;.<\/p>\n<p>Jorge Nieto a Keiko Fujimori: &#8220;Le he sugerido que considere las rutas para la libertad del presidente Castillo, buscando que el pa\u00eds encuentre un espacio de descompresi\u00f3n y despolarizaci\u00f3n&#8221;https:\/\/t.co\/38asZiWiHy<\/p>\n<p>\u2013 Canal N (@canalN_) 14 de julio de 2026 En ese contexto, se\u00f1al\u00f3 que plante\u00f3, como sugerencia, a la presidenta electa realizar acciones simb\u00f3licas dirigidas a las familias de las v\u00edctimas de las protestas ocurridas entre diciembre del 2022 y comienzos del 2023.<\/p>\n<p>&#8220;Le hemos sugerido a la presidenta que haya gestos simb\u00f3licos y pol\u00edticos, que reciba a los comit\u00e9s de familiares de las v\u00edctimas de diciembre de 2022 y 2023. Ellos tienen necesidad de ser escuchados, tienen necesidad de reparaci\u00f3n. Es parte de un conjunto de medidas que le hemos sugerido&#8221;.<\/p>\n<p>Jorge Nieto, l\u00edder del Partido del Buen Gobierno, declara a la prensa luego de reunirse con la Presidenta electa, Keiko Fujimori. (Fotos: Jes\u00fas Saucedo \/@photo.gec)<\/p>\n<p> Nieto indic\u00f3 adem\u00e1s que propuso evaluar alternativas legales respecto a la situaci\u00f3n del expresidente pedro castillo como una forma de contribuir a disminuir la tensi\u00f3n pol\u00edtica en el pa\u00eds, asegurando que no se refiri\u00f3 de forma expresa a un \u201cindulto\u201d.<\/p>\n<p>\u201cEn materia del presidente Pedro Castillo, le he sugerido tambi\u00e9n hoy a la presidenta que considere las rutas para la libertad del presidente Castillo, buscando que el pa\u00eds encuentre un espacio de descompresi\u00f3n y despolarizaci\u00f3n.\u201d.<\/p>\n<p>#EnVivo<\/p>\n<p>Jorge Nieto tras reuni\u00f3n con Keiko Fujimori: Si la posibilidad planteada de revisar la situaci\u00f3n legal de Pedro Castillo est\u00e1 colocada en el marco de una pol\u00edtica simb\u00f3lica de reconciliaci\u00f3n y acercamiento del pa\u00eds, entonces no es una tarea que le competa a este\u2026 pic.twitter.com\/ODQMvCIyMA<\/p>\n<p>\u2013 Canal N (@canalN_) 14 de julio de 2026 &#8220;Le he sugerido que considere las rutas para que eso sea dentro de un marco de Estado de derecho y de la Constituci\u00f3n. Ha tomado nota; en algunos casos ha asentido&#8221;.<\/p>\n<p>De este modo, Nieto Montesinos se suma a otros l\u00edderes pol\u00edticos y excandidatos presidenciales que visitaron a la presidenta electa. <\/p>\n<p>Ayer fue el turno de C\u00e9sar Acu\u00f1a y Carlos Esp\u00e1, quienes mostraron su disposici\u00f3n al di\u00e1logo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El excandidato presidencial y l\u00edder del Partido del Buen Gobierno, Jorge Nietolleg\u00f3 a las oficinas de la presidenta electa Keiko Fujimori para saludarla y mantener un di\u00e1logo con ella. El excandidato presidencial y l\u00edder del Partido del Buen Gobierno, Jorge Nietolleg\u00f3 a las oficinas de la presidenta electa Keiko Fujimori para saludarla y mantener un [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":90273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2420,419],"tags":[],"class_list":["post-90272","post","type-post","status-publish","format-standard","has-post-thumbnail","category-jorge","category-peru"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90272"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90272\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90273"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}