{"id":90238,"date":"2026-07-14T15:37:58","date_gmt":"2026-07-14T18:37:58","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/terror-en-la-via-al-choco-tras-el-secuestro-de-39-pasajeros-de-un-autobus-de-rapido-ochoa-reportan-que-hay-un-soldado-asesinado-y-otros-seis-heridos\/"},"modified":"2026-07-14T15:37:58","modified_gmt":"2026-07-14T18:37:58","slug":"terror-en-la-via-al-choco-tras-el-secuestro-de-39-pasajeros-de-un-autobus-de-rapido-ochoa-reportan-que-hay-un-soldado-asesinado-y-otros-seis-heridos","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/terror-en-la-via-al-choco-tras-el-secuestro-de-39-pasajeros-de-un-autobus-de-rapido-ochoa-reportan-que-hay-un-soldado-asesinado-y-otros-seis-heridos\/","title":{"rendered":"Terror en la v\u00eda al Choc\u00f3: tras el secuestro de 39 pasajeros de un autob\u00fas de R\u00e1pido Ochoa reportan que hay un soldado asesinado y otros seis heridos"},"content":{"rendered":"<p>Noticia<\/p>\n<p>Las autoridades rechazaron este hecho y exigen la liberaci\u00f3n de los secuestrados. Tambi\u00e9n piden abstenerse de movilizarse por la v\u00eda Quibd\u00f3 &#8211; Medell\u00edn<\/p>\n<p>El Ej\u00e9rcito Nacional denunci\u00f3 que 39 personas fueron secuestradas por el ELN en jurisdicci\u00f3n de Quibd\u00f3.  Foto: Suministradas.<\/p>\n<p>PERIODISTA14.07.2026 13:12 Actualizado: 14.07.2026 13:12 <\/p>\n<p>       Una grave crisis humanitaria y de seguridad sacude al occidente del pa\u00eds tras darse a conocer el secuestro masivo de 39 personas en la v\u00eda que comunica a Medell\u00edn con Quibd\u00f3en el sector conocido como Las Toldas, en el departamento del Choc\u00f3. <\/p>\n<p>El hecho, atribuido por las Fuerzas Militares al Frente &#8216;Hern\u00e1ndez El Boche&#8217; del Ej\u00e9rcito de Liberaci\u00f3n Nacional (Eln), escal\u00f3 en las \u00faltimas horas a un escenario de alta confrontaci\u00f3n armada luego de que las tropas que acudieron a la zona de la emergencia. fueron emboscadas por la organizaci\u00f3n subversiva, cobrando la vida de un soldado profesional y dejando a otros seis heridos de gravedad.<\/p>\n<p>De acuerdo con la informaci\u00f3n entregada de manera conjunta por las autoridades, el secuestro masivo se perpetr\u00f3 durante la madrugada de este martes cuando integrantes fFuertemente armados de la estructura ilegal bloquearon el corredor estrat\u00e9gico vial, entre los sectores conocidos como El 18 y Toldas. <\/p>\n<p>El Ej\u00e9rcito Nacional denunci\u00f3 que 39 personas fueron secuestradas por el ELN en jurisdicci\u00f3n de Quibd\u00f3.  Foto:Suministrada.<\/p>\n<p>Aprovechando el tr\u00e1nsito del transporte p\u00fablico intermunicipal, los subversivos obligaron a detener la marcha a dos autobuses de la empresa de transporte de pasajeros R\u00e1pido Ochoa SA, reteniendo ilegalmente a conductores y ocupantes, entre los cuales se ha confirmado la presencia de por lo menos un menor de edad.<\/p>\n<p>El Brigadier General Eduardo Alberto Arias, comandante de la S\u00e9ptima Divisi\u00f3n del Ej\u00e9rcito Nacional, inform\u00f3 que se mantiene comunicaci\u00f3n constante en la zona y se pudo establecer que las v\u00edctimas se encuentran bien, aunque contin\u00faen bajo control de sus captores. <\/p>\n<p>La respuesta gubernamental e institucional se activ\u00f3 de manera inmediata a trav\u00e9s de la Brigada 15 del Ej\u00e9rcito con unidades del Grupo de Infanter\u00eda de Selva No. 9 (Grupi 9) en coordinaci\u00f3n con la Polic\u00eda Nacional, con el fin de desplegar operaciones y lograr la pronta liberaci\u00f3n.<\/p>\n<p>No obstante, en el avance de las tropas para retomar el control absoluto del eje vial, unidades de respuesta cayeron en una violenta emboscada preparada por miembros del Eln. <\/p>\n<p>Este ataque se cobr\u00f3 la vida de un soldado de las Fuerzas Militares y dej\u00f3 a seis uniformados m\u00e1s heridos. con impactos de bala y esquirlas, siendo trasladados de urgencia a centros asistenciales. <\/p>\n<p>La vicepresidenta de la Rep\u00fablica, Francia M\u00e1rquez, expres\u00f3 su en\u00e9rgico rechazo: &#8220;Es absolutamente inaceptable que, en medio de estos hechos, un soldado de las Fuerzas Militares haya sido asesinado y otros seis hayan resultado heridos&#8221;.. La vida y la libertad se respetan&#8221;.<\/p>\n<p>Rechazo de manera contundente las acciones del ELN que hoy mantienen secuestrados a 39 pasajeros, entre ellos menores de edad, en la v\u00eda Quibd\u00f3-Medell\u00edn, poniendo en riesgo la vida, la integridad y la tranquilidad de la poblaci\u00f3n civil. El Choc\u00f3 merece vivir en paz y libre de\u2026<\/p>\n<p>\u2013 Francia M\u00e1rquez Mina (@FranciaMarquezM) 14 de julio de 2026  Ante el cr\u00edtico escenario de alteraciones del orden p\u00fablico, la gobernadora del Choc\u00f3, Nubia Carolina C\u00f3rdoba-Curi, emiti\u00f3 un llamado de urgencia instant\u00e1neo de manera prioritaria a transportadores y viajeros a abstenerse por completo de movilizarse por la v\u00eda Quibd\u00f3 &#8211; Medell\u00edn hasta que se garanticen plenas condiciones de seguridad en la zona. <\/p>\n<p>Por su parte, la empresa Transportes R\u00e1pido Ochoa SA inform\u00f3 oficialmente que, con el fin de proteger la integridad de sus pasajeros y colaboradores, suspender\u00e1 de forma temporal la ruta habitual por el corredor afectado y reanudar\u00e1 sus operaciones desde y hacia el Choc\u00f3 a trav\u00e9s de la v\u00eda Pereira (Risaralda). <\/p>\n<p>Las operaciones militares contin\u00faan activas en el sector para estrechar el cerco sobre los responsables y recuperar la tranquilidad en este territorio hist\u00f3ricamente golpeado por la violencia.<\/p>\n<p>  Sigue toda la informaci\u00f3n de Colombia en Facebook y Twitter, o en nuestro bolet\u00edn semanal. <\/p>\n<p>BOLETINES EL TIEMPO<\/p>\n<p>Reg\u00edstrate en nuestros boletines y recibe noticias en tu correo seg\u00fan tus intereses. Mantente informado con lo que realmente te importa.<\/p>\n<p>NOTICIAS DE GOOGLE EL TIEMPO<\/p>\n<p>S\u00edguenos en GOOGLE NEWS. Mantente siempre actualizado con las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en Google News.<\/p>\n<p>EL TIEMPO WHATSAPP<\/p>\n<p>\u00danete al canal de El Tiempo en WhatsApp para estar al d\u00eda con las noticias m\u00e1s relevantes al momento.<\/p>\n<p>APLICACI\u00d3N EL TIEMPO<\/p>\n<p>Mantente informado con la app de EL TIEMPO. Recibe las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en tu dispositivo.<\/p>\n<p>SUSCR\u00cdBETE AL DIGITAL<\/p>\n<p>Informaci\u00f3n confiable para ti. Suscr\u00edbete a EL TIEMPO y consulta de forma ilimitada nuestros contenidos period\u00edsticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticia Las autoridades rechazaron este hecho y exigen la liberaci\u00f3n de los secuestrados. Tambi\u00e9n piden abstenerse de movilizarse por la v\u00eda Quibd\u00f3 &#8211; Medell\u00edn El Ej\u00e9rcito Nacional denunci\u00f3 que 39 personas fueron secuestradas por el ELN en jurisdicci\u00f3n de Quibd\u00f3. Foto: Suministradas. PERIODISTA14.07.2026 13:12 Actualizado: 14.07.2026 13:12 Una grave crisis humanitaria y de seguridad sacude [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[585,763],"tags":[],"class_list":["post-90238","post","type-post","status-publish","format-standard","has-post-thumbnail","category-colombia","category-medellin"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90238"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90239"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}