{"id":90218,"date":"2026-07-14T14:16:46","date_gmt":"2026-07-14T17:16:46","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/reino-unido-otorgo-reconocimiento-a-joven-venezolano-por-su-labor-como-traductor-en-la-guaira\/"},"modified":"2026-07-14T14:16:46","modified_gmt":"2026-07-14T17:16:46","slug":"reino-unido-otorgo-reconocimiento-a-joven-venezolano-por-su-labor-como-traductor-en-la-guaira","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/14\/reino-unido-otorgo-reconocimiento-a-joven-venezolano-por-su-labor-como-traductor-en-la-guaira\/","title":{"rendered":"Reino Unido otorg\u00f3 reconocimiento a joven venezolano por su labor como traductor en La Guaira"},"content":{"rendered":"<p>La iniciativa de voluntarios venezolanos que participan en la misi\u00f3n humanitaria tras los terremotos registrados el 24 de junio en el pa\u00eds ha recibido reconocimiento por parte de delegaciones extranjeras. Tal es el caso de Israel Rivasun joven de San F\u00e9lix, estado Bol\u00edvar, cuyo apoyo como traductor Durante las labores de rescate en La Guaira ha sido reconocido por el gobierno del Reino Unido.<\/p>\n<p>Mediante una carta oficial, el gobierno brit\u00e1nico honra el compromiso de Rivas y su contribuci\u00f3n como traductor del idioma ingl\u00e9s para los equipos de asistencia internacional que particip\u00f3 en las operaciones de b\u00fasqueda y rescate de sobrevivientes en las zonas afectadas por los sismos en Venezuela.<\/p>\n<p>El joven venezolano comparti\u00f3 la distinci\u00f3n a trav\u00e9s de sus plataformas digitales, manifestando su agradecimiento directo a las autoridades diplom\u00e1ticas del Reino Unido.<\/p>\n<p>\u201cEl equipo de b\u00fasqueda y rescate del Reino Unido fue el primero con el que estuve, me ense\u00f1aron a ser resiliente al momento de enfrentarse a situaciones duras y de gran impacto\u201d, expres\u00f3 Rivas, refiri\u00e9ndose a la carga psicol\u00f3gica impl\u00edcita que demostr\u00f3 el haber transitado por las zonas devastadas por el doble terremoto que, en su opini\u00f3n, \u201cpuede afectar bastante la manera de ver la vida\u201d.<\/p>\n<p>La labor del venezolano inici\u00f3 formalmente con el grupo de b\u00fasqueda y rescate brit\u00e1nico UK-ISARuna experiencia de alto nivel que le permiti\u00f3 conocer al embajador del Reino Unido en Venezuela, colin dickun paso clave que facilit\u00f3 su incorporaci\u00f3n al Equipo M\u00e9dico de Emergencia (EMT) de Ukaid.<\/p>\n<p>Rivas destac\u00f3 que su trabajo no se limit\u00f3 a la interpretaci\u00f3n ling\u00fc\u00edstica, sino que ofreci\u00f3 un acompa\u00f1amiento crucial a familias que atravesaban situaciones de extrema vulnerabilidadmientras los equipos de rescate sumaban esfuerzos para encontrar con vida a sus seres queridos entre los escombros de las estructuras destruidas por los terremotos.<\/p>\n<p>\u201cMi misi\u00f3n fue ser un puente ante la barrera comunicacional, sin embargo, me he encontrado con un mont\u00f3n de emociones al momento de traducir, no es solo un papel o una frase, es la vida o la muerte de un ser querido\u201d, manifest\u00f3.<\/p>\n<p>Entre edificios en ruinas, escombros y el ruido de las ambulancias, el joven oriundo del estado Bol\u00edvar encontr\u00f3 en su fe la fuerza para brindarle apoyo a las personas afectadas por la tragedia.<\/p>\n<p>Rivas inst\u00f3 a la poblaci\u00f3n a no dejarse vencer por el des\u00e1nimo. Los invitamos a observar la fortaleza de los ni\u00f1os, quienes, a pesar de la adversidad, encuentran en las actividades recreativas una oportunidad para sonre\u00edr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa de voluntarios venezolanos que participan en la misi\u00f3n humanitaria tras los terremotos registrados el 24 de junio en el pa\u00eds ha recibido reconocimiento por parte de delegaciones extranjeras. Tal es el caso de Israel Rivasun joven de San F\u00e9lix, estado Bol\u00edvar, cuyo apoyo como traductor Durante las labores de rescate en La Guaira [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":90219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23150,6740,22386,6684,7580,21039,23151,332],"tags":[],"class_list":["post-90218","post","type-post","status-publish","format-standard","has-post-thumbnail","category-israel-rivas","category-la-guaira","category-operaciones-de-rescate","category-reconocimiento","category-reino-unido","category-terremotos-en-venezuela","category-traductor-de-ingles","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=90218"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/90218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/90219"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=90218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=90218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=90218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}