{"id":89760,"date":"2026-07-13T15:19:00","date_gmt":"2026-07-13T18:19:00","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/embajada-de-francia-en-argentina-critica-declaraciones-racistas-de-funcionario-de-mendoza\/"},"modified":"2026-07-13T15:19:00","modified_gmt":"2026-07-13T18:19:00","slug":"embajada-de-francia-en-argentina-critica-declaraciones-racistas-de-funcionario-de-mendoza","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/embajada-de-francia-en-argentina-critica-declaraciones-racistas-de-funcionario-de-mendoza\/","title":{"rendered":"Embajada de Francia en Argentina critica declaraciones &#8220;racistas&#8221; de funcionario de Mendoza"},"content":{"rendered":"<p>   La Embajada de Francia en Argentina conden\u00f3 en\u00e9rgicamente las declaraciones del vicegobernador de la provincia de Mendoza, Hebe Casado, quien describi\u00f3 a la selecci\u00f3n francesa de f\u00fatbol como un &#8220;equipo africano maleducado&#8221; tras la victoria del equipo sobre Paraguay la semana pasada en el Mundial de 2026.<\/p>\n<p>    El domingo, la Embajada dijo que Casado, que defendi\u00f3 sus comentarios, hab\u00eda sido declarado persona non grata en sus instalaciones y dijo que no cooperar\u00eda en reuniones bilaterales con el funcionario.<\/p>\n<p>    Casado, un pol\u00edtico de derecha que es el segundo al mando en la provincia occidental, public\u00f3 un mensaje en X despu\u00e9s de la victoria de Francia por 1-0 sobre Paraguay en los octavos de final del Mundial de 2026, que dec\u00eda: &#8220;Bien hecho, Paraguay. La maleducada selecci\u00f3n africana. No soporto [star striker Kylian] Mbapp\u00e9.&#8221;<\/p>\n<p>    Mbapp\u00e9 fue objeto de cr\u00edticas tras celebrar la victoria de Francia sin aceptar un apret\u00f3n de manos del portero paraguayo Orlando Gill, tras un choque de mal humor.<\/p>\n<p>    En reacci\u00f3n a los comentarios, el embajador de Francia en Argentina, Romain Nadal, public\u00f3 una declaraci\u00f3n en las redes sociales condenando la discriminaci\u00f3n, junto con una captura de pantalla de los comentarios del funcionario provincial.<\/p>\n<p>    &#8220;El orgullo por nuestros colores nunca puede convertirse en una excusa para la discriminaci\u00f3n. Cualquier forma de racismo, antisemitismo o discriminaci\u00f3n basada en el origen, la religi\u00f3n o las circunstancias personales merece el mismo rechazo absoluto e inequ\u00edvoco&#8221;, escribi\u00f3 el embajador.<\/p>\n<p>    &#8220;Competir s\u00ed. Discriminar, nunca. El deporte debe unir, no dividir&#8221;, concluy\u00f3.<\/p>\n<p>    Casado se ha defendido firmemente de la reacci\u00f3n, publicando en X que &#8220;s\u00f3lo las personas inteligentes entienden el sarcasmo&#8221;.<\/p>\n<p>    La vicegobernadora de Mendoza defendi\u00f3 sus comentarios, argumentando que deben entenderse en el contexto de la rivalidad futbol\u00edstica. &#8220;Es parte del folklore del f\u00fatbol. No tiene nada que ver con el racismo&#8221;, afirm\u00f3.<\/p>\n<p>    En una entrevista posterior con una emisora \u200b\u200bde radio de Mendoza, volvi\u00f3 a referirse a Francia como un &#8220;equipo africano&#8221; y se burl\u00f3 de la correcci\u00f3n pol\u00edtica, argumentando que &#8220;todos&#8221; hab\u00edan compartido el mismo pensamiento.<\/p>\n<p>    Las declaraciones del funcionario, que provocaron una fuerte reacci\u00f3n en las redes sociales, fueron inicialmente eclipsadas por un furor similar causado por los comentarios insultantes sobre Mbapp\u00e9 realizados por la senadora paraguaya Celeste Amarilla despu\u00e9s del mismo partido del Mundial.<\/p>\n<p>    Los comentarios racistas de Amarilla provocaron una respuesta indignada del capit\u00e1n de Les Bleus, quien public\u00f3 en l\u00ednea criticando al legislador paraguayo. Tambi\u00e9n fueron condenados por los gobiernos franc\u00e9s y paraguayo, el presidente de la FIFA, Gianni Infantino, e incluso las Naciones Unidas.<\/p>\n<p>        &#8216;No hay lugar a dudas&#8217;<\/p>\n<p>    En declaraciones a la AFP, el embajador Nadal afirm\u00f3 que &#8220;no hay lugar a dudas&#8221; sobre el &#8220;car\u00e1cter racista&#8221; de las declaraciones de Casado. Dijo que &#8220;descalificar\u00edan&#8221; al funcionario &#8220;para trabajar con la Embajada o participar en reuniones a las que asista la Embajada&#8221;.<\/p>\n<p>    &#8220;El racismo no es una opini\u00f3n, es un crimen. No hay lugar para el racismo en la cooperaci\u00f3n franco-argentina&#8221;, dijo a la agencia de noticias.<\/p>\n<p>    El diplom\u00e1tico de m\u00e1s alto rango de Francia en Argentina ha ordenado a su personal que no asista a ninguna reuni\u00f3n bilateral con el gobierno de la provincia de Mendoza en la que est\u00e9 presente Casado, a menos que la funcionaria se retracte de sus declaraciones.<\/p>\n<p>    &#8220;Estamos orgullosos de nuestra diversidad y no toleraremos este ni ning\u00fan otro intento de denigrar o ignorar la nacionalidad de nuestros jugadores&#8221;, dijo el embajador. <\/p>\n<p>    &#8220;\u00bfC\u00f3mo puede un funcionario de un pa\u00eds como Argentina, que orgullosamente dice haber acogido a los inmigrantes con los brazos abiertos, criticar a otro equipo cuyos jugadores tambi\u00e9n son producto de la inmigraci\u00f3n?&#8221;<\/p>\n<p>    El lunes, un d\u00eda despu\u00e9s de la persona non grata declaraci\u00f3n, Casado intensific\u00f3 a\u00fan m\u00e1s la disputa al compartir una publicaci\u00f3n en X de Javier Negre, periodista espa\u00f1ol y copropietario de La Derecha Diarioun medio digital estrechamente alineado con el gobierno de Milei, argumentando que la selecci\u00f3n francesa podr\u00eda ser considerada &#8220;un equipo africano, dado el origen de sus jugadores o de sus padres&#8221;.<\/p>\n<p>    Hablando con los LV10 Opini\u00f3n En su programa de streaming, Casado rechaz\u00f3 de plano las acusaciones de racismo. &#8220;Honestamente, no veo nada racista en el comentario. Si alguien lo toma como racista es porque considera a los africanos como algo inferior. Yo no&#8221;, afirm\u00f3.<\/p>\n<p>     &#8220;Quienes deben dar marcha atr\u00e1s son los que piensan que ser africano es un insulto. No estoy haciendo eso, los estoy poniendo bajo una luz positiva&#8221;, afirm\u00f3.<\/p>\n<p>    En otros comentarios en las redes sociales, Casado describi\u00f3 a Argentina como \u201cel pa\u00eds menos racista del mundo\u201d.<\/p>\n<p>    &#8220;Si algo el resto del mundo deber\u00eda aprender de Argentina es que fuimos de los primeros pa\u00edses en abolir la esclavitud, lo que permiti\u00f3 la mezcla de razas, culturas y religiones. Debemos ser el pa\u00eds menos racista del mundo&#8221;, afirm\u00f3.<\/p>\n<p>        \u2013 TIMES\/AFP\/NA<\/p>\n<p>                noticias relacionadas     <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Embajada de Francia en Argentina conden\u00f3 en\u00e9rgicamente las declaraciones del vicegobernador de la provincia de Mendoza, Hebe Casado, quien describi\u00f3 a la selecci\u00f3n francesa de f\u00fatbol como un &#8220;equipo africano maleducado&#8221; tras la victoria del equipo sobre Paraguay la semana pasada en el Mundial de 2026. El domingo, la Embajada dijo que Casado, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89761,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[253,301,22998,66,1121,22997,22996,22993,16432,624,18789,9131,12966,59,22999,9320,22994,22995,335,339],"tags":[],"class_list":["post-89760","post","type-post","status-publish","format-standard","has-post-thumbnail","category-argentina","category-diplomacy","category-discrimination","category-football","category-france","category-france-embassy-in-argentina","category-french-embassy","category-hebe-casado","category-kylian-mbappe","category-mendoza","category-mendoza-province","category-national-team","category-persona-non-grata","category-politics","category-prejudice","category-racism","category-row","category-sport","category-world-cup-2026"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89760"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89761"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}