{"id":89756,"date":"2026-07-13T15:16:57","date_gmt":"2026-07-13T18:16:57","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/el-gobierno-ya-tendio-el-puente-financiero-hacia-2027-ahora-falta-que-la-economia-real-lo-cruce\/"},"modified":"2026-07-13T15:16:57","modified_gmt":"2026-07-13T18:16:57","slug":"el-gobierno-ya-tendio-el-puente-financiero-hacia-2027-ahora-falta-que-la-economia-real-lo-cruce","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/el-gobierno-ya-tendio-el-puente-financiero-hacia-2027-ahora-falta-que-la-economia-real-lo-cruce\/","title":{"rendered":"El Gobierno ya tendi\u00f3 el puente financiero hacia 2027: ahora falta que la econom\u00eda real lo cruce"},"content":{"rendered":"<p> La lectura posterior del mercado, sin embargo, tambi\u00e9n dej\u00f3 entrever algunos matices. En la city advierten que varios de los supuestos sobre los que se apoya el programa -especialmente de cara a 2027- todav\u00eda deber\u00e1n ser validados, tanto en materia de financiamiento como de acumulaci\u00f3n de reservas y generaci\u00f3n de divisas. En otras palabras, el plan logr\u00f3 despejar buena parte del corto plazo, pero su ejecuci\u00f3n todav\u00eda deber\u00e1 superar varias pruebas, muchas de ellas ajenas al programa: desde la din\u00e1mica pol\u00edtica -del propio oficialismo y la desdibujada oposici\u00f3n- hasta la evoluci\u00f3n de la econom\u00eda local y de la incierta coyuntura internacional.<\/p>\n<p>  El principal interrogante sigue pasando, como casi siempre en la Argentina, por el frente cambiario. Si bien el Tesoro tiene pr\u00e1cticamente cubiertas sus necesidades financieras para 2026 y busca llegar al a\u00f1o pr\u00f3ximo con un colch\u00f3n de u$s3.700 millones, la ejecuci\u00f3n del programa de 2027 -con vencimientos por unos u$s24.900 millones- exige que el Banco Central contin\u00fae acumulando divisas para abastecer al Tesoro, afrontar sus propios compromisos y cumplir con las metas de reservas acordadas con el FMI.<\/p>\n<p>   C\u00e1lculos de Invecq estiman que la autoridad monetaria deber\u00eda comprar alrededor de u$s11.000 millones el a\u00f1o pr\u00f3ximo: unos u$s4.900 millones para venderle al Tesoro, cerca de u$s1.600 millones para afrontar los pagos del Bopreal -la cifra es m\u00e1s alta pero una gran proporci\u00f3n se usa para pagar impuestos- y otros u$s4.500 millones para cumplir con la meta de reservas comprometida con el Fondo a mediados de 2027. En un a\u00f1o electoral, y con el antecedente todav\u00eda fresco de 2025, el desaf\u00edo luce especialmente exigente. Recordemos que en la previa de las \u00faltimas legislativas, la dolarizaci\u00f3n de carteras alcanz\u00f3 los u$s35.000 millones, un registro sin antecedentes y equivalente a m\u00e1s de la mitad del M2 (dinero en efectivo, en cuentas corrientes y en cajas de ahorro), seg\u00fan el BCRA.<\/p>\n<p>  Otro de los puntos que genera debate entre los analistas es la proyecci\u00f3n de captar u$s5.000 millones adicionales en el mercado local durante 2027. El objetivo parece realizable, apoyado en la buena recepci\u00f3n que tuvieron las colocaciones de los bonos AO27 y AO28 -esta semana lanzan el AO29-, aunque el clima electoral podr\u00eda volver un tanto compleja esa tarea.<\/p>\n<p> Todo esto, adem\u00e1s, en un contexto internacional que dejar\u00eda de ser tan favorable como el del primer semestre. Una eventual baja en los precios de los principales productos de exportaci\u00f3n reducir\u00eda el ingreso de divisas, mientras que una econom\u00eda dom\u00e9stica en recuperaci\u00f3n tambi\u00e9n impulsar\u00eda las importaciones y, con ellas, la demanda de d\u00f3lares.<\/p>\n<p> Aun as\u00ed, el Gobierno conserva algunas cartas debajo de la manga. Adem\u00e1s de mantener disponible el swap con EEUU como herramienta para enfrentar eventuales episodios de volatilidad -habr\u00e1 que ver tambi\u00e9n c\u00f3mo impacta un posible resultado adverso para Donald Trump en las legislativas del pr\u00f3ximo 3 de noviembre-, el equipo econ\u00f3mico no descarta la posibilidad de volver a emitir deuda en los mercados internacionales. Hoy esa alternativa sigue siendo costosa -los bonos rinden en torno al 8,5% anual-, aunque una mayor compresi\u00f3n del riesgo pa\u00eds (\u00bf350? puntos) volver\u00eda a acercar al pa\u00eds al mercado voluntario de cr\u00e9dito. En enero existi\u00f3 una ventana para emitir deuda. Ecuador la aprovech\u00f3. Desde entonces, el riesgo pa\u00eds argentino cay\u00f3 cerca de 80 puntos b\u00e1sicos, aunque el aumento de 30 puntos en la tasa del bono del Tesoro estadounidense a 10 a\u00f1os moder\u00f3 parte de esa mejora, seg\u00fan Econviews. El escenario externo, adem\u00e1s, se volvi\u00f3 m\u00e1s desafiante: la Fed de Kevin Warsh empieza a coquetear con una nueva suba de tasas, el conflicto entre Estados Unidos e Ir\u00e1n volvi\u00f3 a escalar y el petr\u00f3leo Brent ya ronda los u$s80.<\/p>\n<p> La cuenta pendiente para el segundo semestre: el repunte de la actividad en su conjunto  Tendido el puente financiero hacia 2027, el desaf\u00edo para el Gobierno pasa por lograr que la econom\u00eda real tenga la fuerza suficiente para cruzarlo. En particular, de que la recuperaci\u00f3n gane consistencia durante el segundo semestre y se convierta en un repunte m\u00e1s generalizado antes de que el calendario electoral empiece a dominar las expectativas de los agentes econ\u00f3micos. Los \u00faltimos datos de la econom\u00eda sugieren que el fuerte retroceso de abril (-1,5% mensual) qued\u00f3 atr\u00e1s, aunque la recuperaci\u00f3n sigue siendo dispar. La industria manufacturera rebot\u00f3 0,4% mensual en mayo y la construcci\u00f3n 6,3%, seg\u00fan el INDEC. En la misma l\u00ednea, el estimador de actividad de EcoGo anticipa un repunte de 0,8%, traccionado por el sector de bienes.<\/p>\n<p> Los primeros datos de junio, en tanto, son mixtos: la confianza del consumidor creci\u00f3 por segundo mes consecutivo (6,4%), aunque los despachos de cemento se hundieron 9,1% mensual y los patentamientos de autos cayeron 7,3% en la misma comparaci\u00f3n.<\/p>\n<p> El problema de fondo es que, aun cuando aparece, el rebote sigue siendo acotado y desigual. Las estimaciones privadas proyectan para 2026 un crecimiento de entre 2,3% y 3,6%, en un escenario marcado por una econom\u00eda de dos velocidades que todav\u00eda no logra cerrar la brecha entre los sectores que avanzan y los que siguen rezagados. Del lado ganador, el segmento energ\u00e9tico acumula una expansi\u00f3n de 27% desestacionalizado desde noviembre de 2023, con la producci\u00f3n de petr\u00f3leo y gas creciendo a tasas de dos d\u00edgitos interanuales gracias a Vaca Muerta, que ya explica cerca de la mitad del super\u00e1vit comercial. <\/p>\n<p>    Del lado perdedor, la industria manufacturera sigue 4,2% por debajo de noviembre de 2023, con una capacidad ociosa cercana al 40%, seg\u00fan el informe de la consultora Industria y Desarrollo (I+D), liderada por Diego Coatz, exdirector ejecutivo de la UIA. I+D advierte, adem\u00e1s, sobre un &#8220;efecto s\u00e1ndwich&#8221;: costos energ\u00e9ticos que suben -la electricidad para grandes usuarios aument\u00f3 79% en d\u00f3lares-, precios industriales que corren detr\u00e1s del IPC y demanda interna que no tracciona. A su vez, el empleo industrial perdi\u00f3 46.500 puestos directos en los \u00faltimos 12 meses y las proyecciones sectoriales anticipan una ca\u00edda de 105.000 empleos -directos e indirectos- para todo 2026.<\/p>\n<p>   Retorn\u00f3 la desinflaci\u00f3n, pero el cr\u00e9dito por ahora no reacciona   La mejor noticia macro del segundo trimestre fue el regreso del proceso de desinflaci\u00f3n. Y continuar\u00e1 en junio: el IPC porte\u00f1o marc\u00f3 1,8%, su tercera desaceleraci\u00f3n consecutiva, y, replicado con ponderadores nacionales, el dato del INDEC -que se conocer\u00e1 este martes- rondar\u00eda 1,8%-1,9%.<\/p>\n<p> De todos modos, julio arranc\u00f3 con alimentos trepando un 2,4% semanal, seg\u00fan el relevamiento de LCG, aunque el promedio del \u00faltimo mes se desaceler\u00f3 a 0,8%. El REM del BCRA volvi\u00f3 a corregir a la baja la proyecci\u00f3n del IPC (2% para junio) y el Top 10 de consultoras espera 30% para todo 2026. Los salarios<br \/>\nformales, en paralelo, hilvanaron un par de meses de recuperaci\u00f3n, tras una ca\u00edda de siete meses al hilo.<\/p>\n<p>Seg\u00fan Empiria, el ingreso disponible de los hogares creci\u00f3 1% real en abril y habr\u00eda vuelto a mejorar en mayo, aunque todav\u00eda se ubica 2,7% por debajo del nivel de noviembre de 2023. La mejora, adem\u00e1s, convive con un consumidor m\u00e1s cauteloso: los gastos fijos ya absorben el 23% del ingreso promedio de los hogares y llegan al 32% entre los sectores de menores recursos. No casualmente, el viceministro Jos\u00e9 Luis Daza reconoci\u00f3 que una parte de la sociedad todav\u00eda no percibe plenamente los beneficios del programa y adelant\u00f3 que el Gobierno trabaja en nuevas herramientas para expandir el cr\u00e9dito, especialmente para la construcci\u00f3n.<\/p>\n<p> Sin embargo, hasta junio el financiamiento al sector privado sigui\u00f3 planchado en medio de un in\u00e9dito nivel de morosidad. Para los pr\u00e9stamos no bancarios, la tasa de irregularidad trep\u00f3 al 28,7% -casi cuatro veces la bancaria- y la de las familias en todo el sistema financiero alcanz\u00f3 12,7% en mayo, seg\u00fan 1816. El dato m\u00e1s inquietante es generacional: entre los menores de 20 a\u00f1os, la morosidad salt\u00f3 de 5,6% a 24,3% en apenas un a\u00f1o.<\/p>\n<p>  En definitiva, el Gobierno ya construy\u00f3 el puente financiero hacia 2027, aunque no exento de riesgos. De todas formas, el verdadero desaf\u00edo ya no parece ser -como en otros a\u00f1os electorales- evitar una nueva crisis, sino convertir la estabilidad macroecon\u00f3mica en una recuperaci\u00f3n m\u00e1s amplia y sostenida. Los pr\u00f3ximos meses dir\u00e1n si el rebote logra dejar atr\u00e1s la l\u00f3gica de una econom\u00eda de dos velocidades o si el crecimiento vuelve a avanzar al ritmo del serrucho, con sectores que consolidan su recuperaci\u00f3n y otros que contin\u00faan rezagados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lectura posterior del mercado, sin embargo, tambi\u00e9n dej\u00f3 entrever algunos matices. En la city advierten que varios de los supuestos sobre los que se apoya el programa -especialmente de cara a 2027- todav\u00eda deber\u00e1n ser validados, tanto en materia de financiamiento como de acumulaci\u00f3n de reservas y generaci\u00f3n de divisas. En otras palabras, el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,42],"tags":[],"class_list":["post-89756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","category-economics"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89756"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89757"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}