{"id":89533,"date":"2026-07-13T04:27:37","date_gmt":"2026-07-13T07:27:37","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/badr-al-boussaidi-ministro-de-asuntos-extranjeros-de-oman-la-guerra-contra-iran-se-revele-a-quel-point-la-politique-dendiguement-etait-un-mythe\/"},"modified":"2026-07-13T04:27:37","modified_gmt":"2026-07-13T07:27:37","slug":"badr-al-boussaidi-ministro-de-asuntos-extranjeros-de-oman-la-guerra-contra-iran-se-revele-a-quel-point-la-politique-dendiguement-etait-un-mythe","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/13\/badr-al-boussaidi-ministro-de-asuntos-extranjeros-de-oman-la-guerra-contra-iran-se-revele-a-quel-point-la-politique-dendiguement-etait-un-mythe\/","title":{"rendered":"Badr Al-Boussa\u00efdi, ministro de Asuntos Extranjeros de Om\u00e1n: \u00abLa guerra contra Ir\u00e1n se rev\u00e9l\u00e9 \u00e0 quel point la politique d&#8217;endiguement \u00e9tait un mythe\u00bb"},"content":{"rendered":"<p>                   Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot).                                    Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr             Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID).         <\/p>\n<p>                              Su tr\u00e1fico ha sido identificado como automatizado (actividad de bot).<\/p>\n<p>                                    Si es un socio autorizado, un suscriptor de Le Monde o si desea solicitar permiso para acceder a este contenido, comun\u00edquese con: licencia[@]grupoelemonde.fr             e incluya una copia de esta p\u00e1gina de error que muestre su direcci\u00f3n IP y su ID de solicitud (RID).         <\/p>\n<p>                    IP: 74.208.218.121<br \/>\nDESHACERSE: ddabfcbaec2e48539c8b000000000001<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot). Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID). Su tr\u00e1fico ha sido identificado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89534,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22913,59],"tags":[],"class_list":["post-89533","post","type-post","status-publish","format-standard","has-post-thumbnail","category-al-boussa","category-politics"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89533"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89534"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}