{"id":89463,"date":"2026-07-12T23:28:03","date_gmt":"2026-07-13T02:28:03","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/argentina-gana-la-ansiada-semifinal-con-inglaterra-tras-otro-calvario\/"},"modified":"2026-07-12T23:28:03","modified_gmt":"2026-07-13T02:28:03","slug":"argentina-gana-la-ansiada-semifinal-con-inglaterra-tras-otro-calvario","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/argentina-gana-la-ansiada-semifinal-con-inglaterra-tras-otro-calvario\/","title":{"rendered":"Argentina gana la ansiada semifinal con Inglaterra tras otro calvario"},"content":{"rendered":"<p>   Un impresionante gol de Juli\u00e1n \u00c1lvarez en la pr\u00f3rroga llev\u00f3 a la Argentina de Lionel Messi a una victoria por 3-1 sobre Suiza en Kansas City el s\u00e1bado, enviando a los campeones defensores a las semifinales de la Copa del Mundo 2026, donde se enfrentar\u00e1n a Inglaterra en un enfrentamiento de alto riesgo.<\/p>\n<p>    \u00c1lvarez rompi\u00f3 el empate 1-1 en el minuto 112 con un disparo espectacular desde fuera del \u00e1rea antes de que Lautaro Mart\u00ednez sellara la victoria en el contraataque ya en el tiempo a\u00f1adido.<\/p>\n<p>    Suiza, que disputaba sus primeros cuartos de final de un Mundial en 72 a\u00f1os, presion\u00f3 a los campeones hasta el final, pero qued\u00f3 en desventaja despu\u00e9s de que Breel Embolo fuera expulsado en el minuto 72 por simulaci\u00f3n, tras haber recibido una segunda tarjeta amarilla.<\/p>\n<p>    Argentina se enfrentar\u00e1 a Inglaterra en la semifinal del mi\u00e9rcoles, un d\u00eda despu\u00e9s de que Francia se enfrente a Espa\u00f1a en la otra eliminatoria de cuartos de final.<\/p>\n<p>    Messi finalmente se enfrentar\u00e1 a Inglaterra en una Copa Mundial por primera vez, exactamente 40 a\u00f1os despu\u00e9s de que el fallecido Diego Maradona produjera una de las actuaciones m\u00e1s definitorias del f\u00fatbol contra los Tres Leones, anotando tanto el infame gol de la &#8216;Mano de Dios&#8217; como el &#8216;Gol del Siglo&#8217; en los cuartos de final de 1986.<\/p>\n<p>    Por primera vez en el torneo, Messi no logr\u00f3 marcar y se mantuvo como m\u00e1ximo goleador con ocho goles junto al franc\u00e9s Kylian Mbapp\u00e9.<\/p>\n<p>    Sin embargo, la estrella del Inter Miami de 39 a\u00f1os registr\u00f3 su d\u00e9cima asistencia en la Copa del Mundo cuando Alexis Mac Allister cabece\u00f3 un tiro de esquina en el minuto 10.<\/p>\n<p>    Argentina ha extendido lo que probablemente ser\u00e1 la \u00faltima Copa del Mundo de Messi por al menos un partido m\u00e1s, pero una vez m\u00e1s tuvo que soportar otra batalla agotadora despu\u00e9s de estrechas victorias sobre Cabo Verde y Egipto.<\/p>\n<p>    &#8220;Hoy no estuvimos al nivel que quer\u00edamos&#8221;, admiti\u00f3 el t\u00e9cnico Lionel Scaloni. &#8220;Sufrimos, pero es muy dif\u00edcil llegar a una semifinal de un Mundial sin sufrir&#8221;.<\/p>\n<p>    Argentina regres\u00f3 a Kansas City, donde hab\u00eda abierto su campa\u00f1a con una impresionante victoria por 3-0 sobre Argelia, buscando dejar atr\u00e1s un comienzo poco convincente en los octavos de final.<\/p>\n<p>    Una vez m\u00e1s les cost\u00f3 imponer su ritmo y, como tantas veces ha sido el caso, s\u00f3lo encontraron un gran avance cuando Messi tuvo un momento de calidad.<\/p>\n<p>    El capit\u00e1n lanz\u00f3 un c\u00f3rner al coraz\u00f3n del \u00e1rea penal suiza, donde Mac Allister super\u00f3 a Embolo y Djibril Sow para rematar de cabeza a Gregor Kobel en el minuto 10.<\/p>\n<p>    El gol desat\u00f3 celebraciones entre los 69.000 espectadores del Arrowhead Stadium, muchos de los cuales esperaban que Argentina finalmente disfrutara de una velada c\u00f3moda.<\/p>\n<p>    Animada por unos pocos cientos de aficionados que viajaban, Suiza se encontr\u00f3 por primera vez en desventaja en el torneo.<\/p>\n<p>        Tarjeta roja por simulaci\u00f3n<\/p>\n<p>    El mayor dramatismo del partido lleg\u00f3 tras el descanso.<\/p>\n<p>    El portero Emiliano Mart\u00ednez rechaz\u00f3 la presi\u00f3n inicial de Suiza, pero los europeos siguieron presionando y finalmente empataron en el minuto 67.<\/p>\n<p>    Dan Ndoye, el atacante m\u00e1s peligroso de Suiza, irrumpi\u00f3 por la izquierda, intercambi\u00f3 pases con Ricardo Rodr\u00edguez y super\u00f3 tranquilamente al carism\u00e1tico portero argentino.<\/p>\n<p>    De repente, Argentina pareci\u00f3 vulnerable, pero las esperanzas de Suiza sufrieron un duro golpe en un controvertido incidente que involucr\u00f3 al VAR.<\/p>\n<p>    El \u00e1rbitro inicialmente amonest\u00f3 a Leandro Paredes por una entrada a Embolo. Sin embargo, despu\u00e9s de revisar las im\u00e1genes en el monitor del campo, concluy\u00f3 que Embolo hab\u00eda simulado la ca\u00edda y en lugar de eso le mostr\u00f3 al delantero una tarjeta amarilla.<\/p>\n<p>    Ya amonestado en la primera parte, Embolo fue expulsado y abandon\u00f3 el terreno de juego angustiado mientras sus compa\u00f1eros protestaban furiosamente.<\/p>\n<p>    &#8220;Las reglas son las reglas&#8230; pero en mi opini\u00f3n es una decisi\u00f3n que mata el juego&#8221;, dijo despu\u00e9s el capit\u00e1n de Suiza, Granit Xhaka.<\/p>\n<p>    &#8220;Es muy doloroso salir as\u00ed. No creo que lo merezcamos&#8221;, a\u00f1adi\u00f3 el t\u00e9cnico Murat Yakin, que calific\u00f3 la intervenci\u00f3n del VAR como &#8220;incorrecta&#8221;.<\/p>\n<p>    Reducida a 10 hombres, Suiza se aferr\u00f3 en busca de la tanda de penaltis, repitiendo la f\u00f3rmula que le hab\u00eda llevado a eliminar a Colombia en octavos de final, mientras el p\u00fablico intentaba rugir al delantero albiceleste.<\/p>\n<p>    Kobel frustr\u00f3 a Messi, Mac Allister y Thiago Almada antes de que \u00c1lvarez, tranquilo durante gran parte de la tarde, lanzara un magn\u00edfico disparo en la escuadra desde fuera del \u00e1rea.<\/p>\n<p>    Fue el primer gol de La Ara\u00f1a en el torneo y dif\u00edcilmente podr\u00eda haber sido m\u00e1s valioso.<\/p>\n<p>    Su compa\u00f1ero delantero Lautaro Mart\u00ednez a\u00f1adi\u00f3 un tercero en el descanso, lo que desat\u00f3 celebraciones en todo el estadio, donde c\u00e1nticos dirigidos a Inglaterra resonaron en las gradas.<\/p>\n<p>    &#8220;Es un partido de f\u00fatbol. No lo hagamos de otra manera&#8221;, dijo Scaloni, intentando bajar la temperatura de cara al encuentro del mi\u00e9rcoles.<\/p>\n<p>    Tras la famosa victoria de Argentina sobre Inglaterra en el Mundial de 1986, cuatro a\u00f1os despu\u00e9s de la Guerra del Atl\u00e1ntico Sur, las dos naciones se volvieron a encontrar en el Mundial de 1998, cuando Argentina se impuso en los penales, y en 2002, cuando Inglaterra sali\u00f3 victoriosa.<\/p>\n<p>     por Guillermo Barros, AFP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un impresionante gol de Juli\u00e1n \u00c1lvarez en la pr\u00f3rroga llev\u00f3 a la Argentina de Lionel Messi a una victoria por 3-1 sobre Suiza en Kansas City el s\u00e1bado, enviando a los campeones defensores a las semifinales de la Copa del Mundo 2026, donde se enfrentar\u00e1n a Inglaterra en un enfrentamiento de alto riesgo. \u00c1lvarez rompi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[253,66,1373,1389,59,335,338,339],"tags":[],"class_list":["post-89463","post","type-post","status-publish","format-standard","has-post-thumbnail","category-argentina","category-football","category-lionel-messi","category-messi","category-politics","category-sport","category-world-cup","category-world-cup-2026"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89463"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89464"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}