{"id":89441,"date":"2026-07-12T21:16:28","date_gmt":"2026-07-13T00:16:28","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/arrestaron-a-cuatro-venezolanos-vinculados-al-tren-de-aragua-en-chile\/"},"modified":"2026-07-12T21:16:28","modified_gmt":"2026-07-13T00:16:28","slug":"arrestaron-a-cuatro-venezolanos-vinculados-al-tren-de-aragua-en-chile","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/arrestaron-a-cuatro-venezolanos-vinculados-al-tren-de-aragua-en-chile\/","title":{"rendered":"Arrestaron a cuatro venezolanos vinculados al Tren de Aragua en Chile"},"content":{"rendered":"<p>Cuatro venezolanos con situaci\u00f3n migratoria irregular quedaron en prisi\u00f3n preventiva por su presunta participaci\u00f3n en delitos atribuidos a c\u00e9lulas del Tren de Aragua cometidos entre 2023 y 2026 en Chile.<\/p>\n<p>El Ministerio P\u00fablico present\u00f3 a los implicados por delitos que incluyen &#8220;secuestro y secuestro con homicidio&#8221;. Los venezolanos quedaron sujetos a un plazo de investigaci\u00f3n de 100 d\u00edas.<\/p>\n<p>Uno de los imputados, alias Miami, quien qued\u00f3 identificado como miembro de la c\u00e9lula Los Cartier. Este hombre es acusado de participar en el secuestro de un ciudadano colombiano en 2023cuando exig\u00edan un pago de rescate por 10 millones de d\u00f3lares.<\/p>\n<p>Mientras que los otros acusados \u200b\u200bforman parte de la c\u00e9lula del Tren de Aragua, Los Shelby. Al parecer, participaci\u00f3n en el secuestro de un ciudadano venezolano en el Barrio Bellavista en 2025. <\/p>\n<p>Seg\u00fan las autoridades, llevaron a la v\u00edctima hasta un inmueble donde la torturaron y asesinaron. Sus restos fueron hallados en febrero de este a\u00f1o.<\/p>\n<p>&#8220;Hubo un secuestro de una persona que se encontr\u00f3 con otros celebrando en el sector de Bellavista cuando, enga\u00f1ado, lo llevaron hasta un domicilio, lo torturaron y finalmente le dieron muerte. Lo enterraron en una maleta y sobre \u00e9l construyeron un radier&#8221;detall\u00f3 el fiscal del Equipo contra el Crimen Organizado y Homicidios (ECOH), Pablo Sabaj.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro venezolanos con situaci\u00f3n migratoria irregular quedaron en prisi\u00f3n preventiva por su presunta participaci\u00f3n en delitos atribuidos a c\u00e9lulas del Tren de Aragua cometidos entre 2023 y 2026 en Chile. El Ministerio P\u00fablico present\u00f3 a los implicados por delitos que incluyen &#8220;secuestro y secuestro con homicidio&#8221;. Los venezolanos quedaron sujetos a un plazo de investigaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[739,2160,1496,710,22896,3370,332],"tags":[],"class_list":["post-89441","post","type-post","status-publish","format-standard","has-post-thumbnail","category-chile","category-detenidos","category-latinoamerica","category-mundo","category-prision-preventiva","category-venezolanos","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89441"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89442"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}