{"id":89435,"date":"2026-07-12T21:16:31","date_gmt":"2026-07-13T00:16:31","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/desalojaron-a-damnificados-que-ocuparon-los-alrededores-del-panteon-nacional-tras-los-terremotos\/"},"modified":"2026-07-12T21:16:31","modified_gmt":"2026-07-13T00:16:31","slug":"desalojaron-a-damnificados-que-ocuparon-los-alrededores-del-panteon-nacional-tras-los-terremotos","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/desalojaron-a-damnificados-que-ocuparon-los-alrededores-del-panteon-nacional-tras-los-terremotos\/","title":{"rendered":"Desalojaron a damnificados que ocuparon los alrededores del Pante\u00f3n Nacional tras los terremotos."},"content":{"rendered":"<p>las autoridades desalojaron este domingo a los damnificados que hab\u00edan levantado un campamento de carpas en los alrededores del Pante\u00f3n Nacionalen la parroquia Altagracia de Caracas, desde los terremotos del 24 de junio.  <\/p>\n<p>La noticia se conoci\u00f3 a trav\u00e9s de redes sociales, donde circularon fotograf\u00edas del campamento antes y despu\u00e9s del desalojo, las cuales fueron difundidas tambi\u00e9n por el periodista Robert Lobo.  <\/p>\n<p>Las im\u00e1genes contrastan la situaci\u00f3n previa.con varias carpas dispuestas en los espacios que rodean el Mausoleo donde reposan los restos del Libertador, Sim\u00f3n Bol\u00edvar, con el estado actual del lugar, ahora completamente despejado. <\/p>\n<p>Los damnificados hab\u00edan optado por instalarse en ese punto de la ciudad tras perder sus viviendas o verse imposibilitados de regresar a ellas por da\u00f1os estructurales derivados de los terremotos de 7,2 y 7,5 de magnitud.  <\/p>\n<p>La cercan\u00eda con el centro de Caracas y la visibilidad del sitio \u2014dada su condici\u00f3n de espacio patrio\u2014 convirtieron el campamento en un punto de atenci\u00f3n p\u00fablica desde las semanas posteriores a la tragedia. <\/p>\n<p>Aunque no hay versiones oficiales, seg\u00fan versiones estos damnificados fueron llevados a refugios temporales en La Guaira y colegios habilitados como cuentos en distintas zonas en la misma Caracas. <\/p>\n<p>De acuerdo con el \u00faltimo balance del gobierno, actualmente se disponen 108 campamentos transitorios, donde permanecen unas 19.583 personas. <\/p>\n<p>#12Jul Damnificados que se encontraron refugiados en los alrededores del Pante\u00f3n Nacional fueron desalojados. La mayor\u00eda fueron reubicados en refugios de La Guaira, mientras que otros los reubicaron en colegios de Caracas. pic.twitter.com\/aeCzyI17Qo<\/p>\n<p>\u2013 Robert Lobo (@RobertLobo_) 12 de julio de 2026 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>las autoridades desalojaron este domingo a los damnificados que hab\u00edan levantado un campamento de carpas en los alrededores del Pante\u00f3n Nacionalen la parroquia Altagracia de Caracas, desde los terremotos del 24 de junio. La noticia se conoci\u00f3 a trav\u00e9s de redes sociales, donde circularon fotograf\u00edas del campamento antes y despu\u00e9s del desalojo, las cuales fueron [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6137,5670,21041,21039,332],"tags":[],"class_list":["post-89435","post","type-post","status-publish","format-standard","has-post-thumbnail","category-caracas","category-damnificados","category-terremotos","category-terremotos-en-venezuela","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89435"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89436"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}