{"id":89419,"date":"2026-07-12T18:36:49","date_gmt":"2026-07-12T21:36:49","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/asesinan-a-dos-personas-en-san-ignacio-de-velasco\/"},"modified":"2026-07-12T18:36:49","modified_gmt":"2026-07-12T21:36:49","slug":"asesinan-a-dos-personas-en-san-ignacio-de-velasco","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/asesinan-a-dos-personas-en-san-ignacio-de-velasco\/","title":{"rendered":"Asesinan a dos personas en San Ignacio de Velasco"},"content":{"rendered":"<p>           Dos personas fueron asesinadas este fin de semana en el municipio de San Ignacio de Velasco, del departamento de Santa Cruz. La Polic\u00eda inici\u00f3 las investigaciones para esclarecer las circunstancias del hecho y dar con los responsables.<\/p>\n<p>    De acuerdo con los informes preliminares, las v\u00edctimas fueron encontradas sin vida en un galp\u00f3n ubicado en el barrio San Miguel. Ambos cuerpos presentaban heridas ocasionadas por proyectiles de arma de fuego.<\/p>\n<p>    Efectivos policiales llegaron al lugar y realizaron el levantamiento legal de los cuerpos, que posteriormente fueron trasladados a la morgue del municipio con multas investigativos.<\/p>\n<p>    Hasta el momento, se desconoce la identidad de las personas fallecidas y las circunstancias en las que ocurri\u00f3 el hecho. La Polic\u00eda contin\u00faa con las investigaciones y no descarta ninguna hip\u00f3tesis para esclarecer el caso; entre las l\u00edneas investigativas se encuentra la posibilidad de que se trate de un ajuste de cuentas. (ABI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos personas fueron asesinadas este fin de semana en el municipio de San Ignacio de Velasco, del departamento de Santa Cruz. La Polic\u00eda inici\u00f3 las investigaciones para esclarecer las circunstancias del hecho y dar con los responsables. De acuerdo con los informes preliminares, las v\u00edctimas fueron encontradas sin vida en un galp\u00f3n ubicado en el [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":89420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[525,895],"tags":[],"class_list":["post-89419","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bolivia","category-policial"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89419"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89420"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}