{"id":89399,"date":"2026-07-12T17:17:11","date_gmt":"2026-07-12T20:17:11","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/videos-tension-en-segovia-por-enfrentamientos-por-operativo-en-la-mina-frontera-gold-comunidades-denuncian-que-hay-familias-afectadas-y-un-muerto\/"},"modified":"2026-07-12T17:17:11","modified_gmt":"2026-07-12T20:17:11","slug":"videos-tension-en-segovia-por-enfrentamientos-por-operativo-en-la-mina-frontera-gold-comunidades-denuncian-que-hay-familias-afectadas-y-un-muerto","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/videos-tension-en-segovia-por-enfrentamientos-por-operativo-en-la-mina-frontera-gold-comunidades-denuncian-que-hay-familias-afectadas-y-un-muerto\/","title":{"rendered":"V\u00eddeos | Tensi\u00f3n en Segovia por enfrentamientos por operativo en la mina Frontera Gold: comunidades denuncian que hay familias afectadas y un muerto"},"content":{"rendered":"<p>Noticia<\/p>\n<p>Comunidades del Nordeste antioque\u00f1o denuncian uso desproporcionado de gases y armas de fuego en un procedimiento de la Polic\u00eda contra la miner\u00eda.<\/p>\n<p>Protestas por paro minero en Segovia  Foto: cortesia<\/p>\n<p>PERIODISTA12.07.2026 10:27 Actualizado: 12.07.2026 12:28 <\/p>\n<p>       El municipio de Segovia, en el Nordeste de Antioquia, vivi\u00f3 en la madrugada de este domingo 12 de julio una jornada de alta tensi\u00f3n y graves alteraciones del orden p\u00fablico tras un operativo de la Polic\u00eda Nacional en una mina de la zona. <\/p>\n<p>La intervenci\u00f3n, orientada inicialmente a un allanamiento contra la miner\u00eda ilegal en la mina Frontera Gold, desencaden\u00f3 fuertes enfrentamientos entre el Grupo de Operaciones Especiales (GOES) y los mineros artesanales, quienes rechazan la acci\u00f3n al considerar que este yacimiento representa el sustento econ\u00f3mico de cientos de familias en la regi\u00f3n.<\/p>\n<p>De acuerdo con los testimonios de los habitantes y trabajadores, el procedimiento comenz\u00f3 entre las 2:30 y las 3:00 de la ma\u00f1ana. con el ingreso de aproximadamente 150 uniformados. <\/p>\n<p>Los manifestantes y l\u00edderes locales denunciaron que las autoridades irrumpieron lanzando gases lacrim\u00f3genos y accionando armas de fuego sin realizar el debido proceso ni notificar la orden de allanamiento. <\/p>\n<p>Si bien la situaci\u00f3n gener\u00f3 resistencia en la zona, la situaci\u00f3n escal\u00f3 r\u00e1pidamente despu\u00e9s del procedimiento.<\/p>\n<p>Hubo informes de protestas, explosiones, quejas de llantas y disturbios en diferentes sectores del municipio.<\/p>\n<p>La gravedad de los hechos aument\u00f3 al reportarse tres personas heridas y la muerte de uno de los mineros artesanales.<\/p>\n<p>Seg\u00fan las primeras versiones, el fallecimiento no se dio en la zona del operativo, sino que se produjo durante las protestas posteriores, presuntamente cuando un uniformado dispar\u00f3 hacia el suelo y el proyecto rebot\u00f3 impactando a la v\u00edctima. <\/p>\n<p>Por ahora no hay claridad si esta situaci\u00f3n fue con el Ej\u00e9rcito, que hac\u00eda presencia en un puesto de control en el lugar de los hechos, ya que desde la Polic\u00eda negaron el hecho seg\u00fan las investigaciones iniciales.<\/p>\n<p>Las protestas y la concentraci\u00f3n de los mineros se han trasladado a las instalaciones de la Electrificadora.y se advierte que las movilizaciones podr\u00edan extenderse en las pr\u00f3ximas horas si no se brindan garant\u00edas de seguridad.<\/p>\n<p>Desde la Gobernaci\u00f3n de Antioquia inform\u00f3 que se avanza en un Consejo de Seguridad para coordinar la respuesta institucional y contener la situaci\u00f3n.<\/p>\n<p>  Sigue toda la informaci\u00f3n de Colombia en Facebook y Twitter, o en nuestro bolet\u00edn semanal. <\/p>\n<p>BOLETINES EL TIEMPO<\/p>\n<p>Reg\u00edstrate en nuestros boletines y recibe noticias en tu correo seg\u00fan tus intereses. Mantente informado con lo que realmente te importa.<\/p>\n<p>NOTICIAS DE GOOGLE EL TIEMPO<\/p>\n<p>S\u00edguenos en GOOGLE NEWS. Mantente siempre actualizado con las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en Google News.<\/p>\n<p>EL TIEMPO WHATSAPP<\/p>\n<p>\u00danete al canal de El Tiempo en WhatsApp para estar al d\u00eda con las noticias m\u00e1s relevantes al momento.<\/p>\n<p>APLICACI\u00d3N EL TIEMPO<\/p>\n<p>Mantente informado con la app de EL TIEMPO. Recibe las \u00faltimas noticias, coberturas, historias y an\u00e1lisis directamente en tu dispositivo.<\/p>\n<p>SUSCR\u00cdBETE AL DIGITAL<\/p>\n<p>Informaci\u00f3n confiable para ti. Suscr\u00edbete a EL TIEMPO y consulta de forma ilimitada nuestros contenidos period\u00edsticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noticia Comunidades del Nordeste antioque\u00f1o denuncian uso desproporcionado de gases y armas de fuego en un procedimiento de la Polic\u00eda contra la miner\u00eda. Protestas por paro minero en Segovia Foto: cortesia PERIODISTA12.07.2026 10:27 Actualizado: 12.07.2026 12:28 El municipio de Segovia, en el Nordeste de Antioquia, vivi\u00f3 en la madrugada de este domingo 12 de julio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[585,763],"tags":[],"class_list":["post-89399","post","type-post","status-publish","format-standard","has-post-thumbnail","category-colombia","category-medellin"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89399"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89400"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}