{"id":89381,"date":"2026-07-12T17:15:56","date_gmt":"2026-07-12T20:15:56","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/lluvias-causaron-inundaciones-en-campamentos-temporales-de-damnificados-en-la-guaira\/"},"modified":"2026-07-12T17:15:56","modified_gmt":"2026-07-12T20:15:56","slug":"lluvias-causaron-inundaciones-en-campamentos-temporales-de-damnificados-en-la-guaira","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/lluvias-causaron-inundaciones-en-campamentos-temporales-de-damnificados-en-la-guaira\/","title":{"rendered":"Lluvias causaron inundaciones en campamentos temporales de damnificados en La Guaira"},"content":{"rendered":"<p>Las fuertes lluvias registradas este s\u00e1bado 11 de julio causaron inundaciones en los campamentos temporales que ocupan las familias damnificadas por el doblete s\u00edsmico en el estado La Guaira. Tras varias horas de precipitaciones, la situaci\u00f3n de los afectados por los terremotos se agrav\u00f3.<\/p>\n<p>A trav\u00e9s de un video difundido en redes sociales, se evidencia c\u00f3mo se inund\u00f3 el espacio donde se encuentran instaladas las carpas. esta situacion oblig\u00f3 a que todas las personas que se encontraban en el lugar abandonaran sus carpas. <\/p>\n<p>En el video se explica que esta situaci\u00f3n se present\u00f3. en las instalaciones de la Universidad Mar\u00edtima del Caribe, en Catia La Mar. En este lugar, adem\u00e1s de albergar a los afectados, opera un centro de acopio. Los afectados mostraron c\u00f3mo se acumul\u00f3 el agua en los espacios que usan para pernoctar.<\/p>\n<p>&#8220;As\u00ed nos encontramos los refugiados en la Universidad Mar\u00edtima bajo la lluvia. Nos estamos inundando por completo y as\u00ed pretendemos que estemos bien&#8221;expres\u00f3 uno de los afectados. En el video se observa c\u00f3mo todos trabajan para sacar el agua acumulada en el campamento.<\/p>\n<p>Es de recordar que el pasado 24 de junio se registr\u00f3 un doble terremoto en Venezuela que afect\u00f3 principalmente al estado La Guaira. En consecuencia, 190 edificios colapsaron, mientras que otros cientos registraron da\u00f1os que impiden su habitabilidad.<\/p>\n<p>La tragedia dej\u00f3 miles de familias sin hogar, por lo que muchos de ellos se encuentran refugiados en campamentos temporales. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fuertes lluvias registradas este s\u00e1bado 11 de julio causaron inundaciones en los campamentos temporales que ocupan las familias damnificadas por el doblete s\u00edsmico en el estado La Guaira. Tras varias horas de precipitaciones, la situaci\u00f3n de los afectados por los terremotos se agrav\u00f3. A trav\u00e9s de un video difundido en redes sociales, se evidencia [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22883,6136,5670,4083,6740,3216,1407,332],"tags":[],"class_list":["post-89381","post","type-post","status-publish","format-standard","has-post-thumbnail","category-campamentos-temporales","category-ciudad","category-damnificados","category-inundaciones","category-la-guaira","category-lluvias","category-noticias","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89381"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89382"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}