{"id":89313,"date":"2026-07-12T12:26:49","date_gmt":"2026-07-12T15:26:49","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/nuevo-sismo-de-magnitud-36-sacudio-la-guaira-la-noche-del-sabado-segun-funvisis\/"},"modified":"2026-07-12T12:26:49","modified_gmt":"2026-07-12T15:26:49","slug":"nuevo-sismo-de-magnitud-36-sacudio-la-guaira-la-noche-del-sabado-segun-funvisis","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/nuevo-sismo-de-magnitud-36-sacudio-la-guaira-la-noche-del-sabado-segun-funvisis\/","title":{"rendered":"Nuevo sismo de magnitud 3,6 sacudi\u00f3 La Guaira la noche del s\u00e1bado, seg\u00fan Funvisis"},"content":{"rendered":"<p>La Fundaci\u00f3n Venezolana de Investigaciones Sismol\u00f3gicas (Funvisis) report\u00f3 la noche de este s\u00e1bado 11 de julio un sismo de magnitud 3,6, con epicentro ubicado a cinco kil\u00f3metros al noroeste de Naiguat\u00e1, en La Guaira, como parte de la actividad s\u00edsmica que persiste tras los terremotos del pasado 24 de junio. <\/p>\n<p>El evento gener\u00f3 reportes inmediatos por parte de las poblaciones del litoral central, quienes permanecer alerta ante la inestabilidad del terreno. Por este motivo, los equipos de monitoreo t\u00e9cnico mantienen la vigilancia sobre las fallas activas de la regi\u00f3n septentrional del pa\u00eds.<\/p>\n<p>Los analistas del instituto oficial procesaron los par\u00e1metros de origen del temblor mediante su red de estaciones sismol\u00f3gicas automatizadas. Seg\u00fan el informe preliminar de Funvisis, el movimiento tel\u00farico ocurri\u00f3 a las 11:02 p.m.estafa una profundidad de 9,9 kil\u00f3metros.<\/p>\n<p>El epicentro fue localizado en las coordenadas 10.640\u00b0 norte y 66.776\u00b0 oeste, a cinco kil\u00f3metros al noroeste de Naiguat\u00e1. Esta ubicaci\u00f3n coincide con el \u00e1rea de influencia de las fracturas tect\u00f3nicas  que liberaron energ\u00eda durante el mes pasado.<\/p>\n<p>Continuidad de la secuencia s\u00edsmicaDe este modo, la sismicidad del sector responde al reacomodo natural de los bloques de la corteza terrestre en el norte de Venezuela. El nuevo evento se suma a la secuencia de r\u00e9plicas registradas desde los terremotos de magnitud 7,2 y 7,5 que sacudieron la regi\u00f3n central del pa\u00eds, especialmente el estado La Guairadonde contin\u00faan las labores de recuperaci\u00f3n y reconstrucci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n Venezolana de Investigaciones Sismol\u00f3gicas (Funvisis) report\u00f3 la noche de este s\u00e1bado 11 de julio un sismo de magnitud 3,6, con epicentro ubicado a cinco kil\u00f3metros al noroeste de Naiguat\u00e1, en La Guaira, como parte de la actividad s\u00edsmica que persiste tras los terremotos del pasado 24 de junio. El evento gener\u00f3 reportes inmediatos [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6913,6740,22859,21713,332],"tags":[],"class_list":["post-89313","post","type-post","status-publish","format-standard","has-post-thumbnail","category-funvisis","category-la-guaira","category-naiguata","category-sismo-en-venezuela","category-venezuela"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89313"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89314"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}