{"id":89155,"date":"2026-07-12T02:29:35","date_gmt":"2026-07-12T05:29:35","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/grua-telescopica-se-volco-en-la-autopista-caracas-la-guaira-y-provoco-retraso-vehicular-por-derrame-de-gasoil\/"},"modified":"2026-07-12T02:29:35","modified_gmt":"2026-07-12T05:29:35","slug":"grua-telescopica-se-volco-en-la-autopista-caracas-la-guaira-y-provoco-retraso-vehicular-por-derrame-de-gasoil","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/grua-telescopica-se-volco-en-la-autopista-caracas-la-guaira-y-provoco-retraso-vehicular-por-derrame-de-gasoil\/","title":{"rendered":"Gr\u00faa telesc\u00f3pica se volc\u00f3 en la autopista Caracas-La Guaira y provoc\u00f3 retraso vehicular por derrame de gasoil."},"content":{"rendered":"<p>Una gr\u00faa telesc\u00f3pica volc\u00f3 la ma\u00f1ana de este s\u00e1bado en la autopista Caracas-La Guaira, en sentido hacia el Litoral Central, y provoc\u00f3 un derrame de combustible tipo gasoil en la v\u00eda. El accidente obstaculiz\u00f3 el libre tr\u00e1nsito en la arteria principal vial que comunica a la capital con el estado La Guaira. <\/p>\n<p>Los conductores particulares y de carga pesada deb\u00edan disminuir la velocidad de desplazamiento, lo que gener\u00f3 un fuerte retraso vehicular en la zona.<\/p>\n<p>El comisionado jefe de la Polic\u00eda de Chacao, Alberto Prato.confirm\u00f3 el siniestro a trav\u00e9s de sus redes sociales y comparti\u00f3 un video en su cuenta de X para alertar a la ciudadan\u00eda sobre las condiciones de la autopista.<\/p>\n<p>En el video, los usuarios pudieron observar la maquinaria pesada recostada directamente sobre el muro de concreto que divide ambos sentidos de las v\u00edas.<\/p>\n<p>Derrame de hidrocarburo y control de tr\u00e1nsitoEn consecuencia, el vertido de gasoil afect\u00f3 la adherencia del asfaltado, incrementando el riesgo de nuevos incrementos en el sector.<\/p>\n<p>La grabaci\u00f3n del hecho muestra que el combustible proced\u00eda de un barril que la gr\u00faa transportaba consigo al momento del suceso. <\/p>\n<p>Ayer tos y pendientes:11:30am, 11\/07\/autopista caracas la Guaira a la altura de 300mts de la estaci\u00f3n de la guardia sentido La Guaira, accidente de tr\u00e1nsito con una maquinar\u00eda (Gr\u00faa Telesc\u00f3pica), se desprendi\u00f3 de el cami\u00f3n y tuvo un gran derrame de gasoil no hubo ning\u00fan herido. pic.twitter.com\/WReqR75cqf<\/p>\n<p>\u2013 Alberto J. Prato (@albertoprato02) 11 de julio de 2026 Por otra parte, la contingencia vial oblig\u00f3 a los funcionarios de la Guardia Nacional Bolivariana (GNB) a restringir parcialmente el paso vehicular en el terreno para evitar que hubiera un mayor colapso de tr\u00e1fico.<\/p>\n<p>Las comisiones de seguridad ciudadana no precisaron las causas t\u00e9cnicas o humanas que provocaron el volcamiento del transporte de carga.<\/p>\n<p>Hasta el momento del reporte, las autoridades tampoco conocen el estado de salud de la persona que manejaba la gr\u00faa ni determinaron la hora exacta en la que despejar\u00edan la autopista en su totalidad para normalizar la circulaci\u00f3n habitual.<\/p>\n<p>Los cuerpos civiles eval\u00faan si la m\u00e1quina se dirige hacia la zona de desastre en La Guaira para prestar apoyo en las labores de remoci\u00f3n de escombros dejados por los terremotos del 24 de junio. Lo que se sabe, es que este tipo de veh\u00edculos cumple un rol log\u00edstico clave en las \u00e1reas colapsadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una gr\u00faa telesc\u00f3pica volc\u00f3 la ma\u00f1ana de este s\u00e1bado en la autopista Caracas-La Guaira, en sentido hacia el Litoral Central, y provoc\u00f3 un derrame de combustible tipo gasoil en la v\u00eda. El accidente obstaculiz\u00f3 el libre tr\u00e1nsito en la arteria principal vial que comunica a la capital con el estado La Guaira. Los conductores particulares [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20844,6740,865,332,22842],"tags":[],"class_list":["post-89155","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gasoil","category-la-guaira","category-sucesos","category-venezuela","category-volcamiento"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89155"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89156"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}