{"id":89153,"date":"2026-07-12T02:29:36","date_gmt":"2026-07-12T05:29:36","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/el-gobierno-calculo-que-al-menos-25-000-viviendas-se-necesitaran-para-afectados-por-terremotos\/"},"modified":"2026-07-12T02:29:36","modified_gmt":"2026-07-12T05:29:36","slug":"el-gobierno-calculo-que-al-menos-25-000-viviendas-se-necesitaran-para-afectados-por-terremotos","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/el-gobierno-calculo-que-al-menos-25-000-viviendas-se-necesitaran-para-afectados-por-terremotos\/","title":{"rendered":"El gobierno calcul\u00f3 que al menos 25.000 viviendas se necesitar\u00e1n para afectados por terremotos"},"content":{"rendered":"<p>Al menos 25.000 es el n\u00famero de viviendas que se necesitar\u00e1n para las personas que perdieron sus casas por los terremotos del 24 de junio, de acuerdo con lo estimado este s\u00e1bado por el presidente de la Asamblea Nacional (AN), Jorge Rodr\u00edguez. <\/p>\n<p>Durante una rueda de prensa, el funcionario asegur\u00f3 que su hermana y mandataria encargada de Venezuela, Delcy Rodr\u00edguez, entregar\u00e1 las primeras 200 viviendas \u201cla pr\u00f3xima semana\u201dsin ofrecer m\u00e1s detalles. <\/p>\n<p>El alto funcionario indic\u00f3 que el n\u00famero de personas sin viviendas, hasta ahora de casi 18.000, \u201cseguramente va a aumentar\u201d a medida que avance el proceso de inspecci\u00f3n de las edificaciones que sufrieron da\u00f1os. <\/p>\n<p>Es por ello, que las autoridades tienen previsto comenzar este mismo s\u00e1bado un censo biom\u00e9trico en los campamentos transitorios habilitados en Caracas, Miranda y La Guaira, este \u00faltimo el m\u00e1s afectado por los terremotos, con el fin de saber con precisi\u00f3n \u201ccu\u00e1ntas viviendas nuevas se necesitan\u201d, dijo. <\/p>\n<p>\u201cNosotros tenemos que apurarnos en resolver el tema de las viviendas\u201d, afirm\u00f3 Rodr\u00edguez, porque, se\u00f1al\u00f3, muchas escuelas y centros escolares est\u00e1n sirviendo de campamentos temporales. <\/p>\n<p>Por ello, el Gobierno trabaja \u201caceleradamente\u201d para tener listos entre septiembre y octubre.cuando comienza el pr\u00f3ximo per\u00edodo escolar, unos \u201ccampamentos unifamiliares\u201d donde estar\u00e1n de forma temporal aquellas personas que actualmente se encuentran en las escuelas. <\/p>\n<p>B\u00fasqueda de terrenos para nuevas casas El diputado explic\u00f3 tambi\u00e9n que hay una \u201cb\u00fasqueda acelerada de espacios para construir ciudades y viviendas antis\u00edsmicas\u201d con \u201curbanismos, escuelas, canchas, centros comerciales y con actividad para que las personas puedan sentirse a gusto\u201d. <\/p>\n<p>Seg\u00fan el presidente del Parlamento, se permiti\u00f3 un sobrevuelo en La Guaira ubicar unos 40 terrenos que suman 584.000 metros cuadrados para la construcci\u00f3n de edificaciones bajas, de pocos pisos. <\/p>\n<p>Rodr\u00edguez explic\u00f3 que se est\u00e1n haciendo estudios geol\u00f3gicos y de suelo para determinar qu\u00e9 construcci\u00f3n se puede hacer. Precis\u00f3 que estos terrenos est\u00e1n ubicados en zonas planas, al pie de la monta\u00f1a o en mesetas aptas para aplanamiento. <\/p>\n<p>Durante una rueda de prensa este s\u00e1bado, Jorge Rodr\u00edguez respondi\u00f3 preguntas sobre tres temas puntuales. Neg\u00f3 que los escombros est\u00e9n siendo arrojados al mar; anunci\u00f3 que pr\u00f3ximamente ser\u00e1n entregadas 200 nuevas viviendas para los afectados; y, al ser consultado sobre una\u2026 pic.twitter.com\/kAvV7edAUr<\/p>\n<p>\u2013 Sergio Novelli (@SergioNovelliE) 11 de julio de 2026 Viviendas prefabricadas Esta semana, el subsecretario general de la ONU para Asuntos Humanitarios, Tom Fletcher, dijo a la agencia de noticias EFE desde La Guaira que el plan del Gobierno venezolano, apoyado por Naciones Unidas, consiste, entre otros, en llevar al pa\u00eds viviendas prefabricadas para poder solucionar el problema habitacional. <\/p>\n<p>Fletcher asegur\u00f3 que la organizaci\u00f3n multilateral ya est\u00e1 \u201crecaudando dinero\u201d para la puesta en marcha del plan. <\/p>\n<p>El diputado dijo que la jefa de Estado est\u00e1 \u201cenviando cartas a otros pa\u00edses donde se encuentran activos retenidos que pertenecen a Venezuela\u201d y que, adem\u00e1s, est\u00e1 \u201cen este momento haciendo todo ese proceso de ingenier\u00eda financiera para contar con los recursos a mano y r\u00e1pido\u201d. <\/p>\n<p>En este sentido, Delcy Rodr\u00edguez inform\u00f3 sobre conversaciones con pa\u00edses como EE UU y Brasil e instituciones como el Fondo Monetario Internacional (FMI) y el Banco Mundial. para adelantar el proceso de recuperaci\u00f3n tras los terremotos. <\/p>\n<p>La jefa de Estado tambi\u00e9n envi\u00f3 una carta al rey brit\u00e1nico Carlos III solicitando la liberaci\u00f3n del oro \u201cretenido\u201d en el Banco de Inglaterra con el fin de usar esos recursos en el proceso de recuperaci\u00f3n. <\/p>\n<p>De momento, los terremotos de magnitud 7,2 y 7,5 han dejado hasta el momento 4.333 fallecidos, seg\u00fan cifras del gobierno. <\/p>\n<p>Con informaci\u00f3n de EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 25.000 es el n\u00famero de viviendas que se necesitar\u00e1n para las personas que perdieron sus casas por los terremotos del 24 de junio, de acuerdo con lo estimado este s\u00e1bado por el presidente de la Asamblea Nacional (AN), Jorge Rodr\u00edguez. Durante una rueda de prensa, el funcionario asegur\u00f3 que su hermana y mandataria [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":89154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5670,7135,21041,21039,332,4483],"tags":[],"class_list":["post-89153","post","type-post","status-publish","format-standard","has-post-thumbnail","category-damnificados","category-jorge-rodriguez","category-terremotos","category-terremotos-en-venezuela","category-venezuela","category-viviendas"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89153"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89153\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89154"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}