{"id":89131,"date":"2026-07-12T02:28:47","date_gmt":"2026-07-12T05:28:47","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/hugh-white-especialista-en-defensa-il-est-illusoire-de-croire-que-les-etats-unis-joueront-pour-laustralie-le-role-quils-ont-assume-par-le-passe\/"},"modified":"2026-07-12T02:28:47","modified_gmt":"2026-07-12T05:28:47","slug":"hugh-white-especialista-en-defensa-il-est-illusoire-de-croire-que-les-etats-unis-joueront-pour-laustralie-le-role-quils-ont-assume-par-le-passe","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/07\/12\/hugh-white-especialista-en-defensa-il-est-illusoire-de-croire-que-les-etats-unis-joueront-pour-laustralie-le-role-quils-ont-assume-par-le-passe\/","title":{"rendered":"Hugh White, especialista en defensa: \u00abIl est illusoire de croire que les Etats-Unis joueront pour l&#8217;Australie le r\u00f4le qu&#8217;ils ont assum\u00e9 par le pass\u00e9\u00bb"},"content":{"rendered":"<p>                   Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot).                                    Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr             Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID).         <\/p>\n<p>                              Su tr\u00e1fico ha sido identificado como automatizado (actividad de bot).<\/p>\n<p>                                    Si es un socio autorizado, un suscriptor de Le Monde o si desea solicitar permiso para acceder a este contenido, comun\u00edquese con: licencia[@]grupoelemonde.fr             e incluya una copia de esta p\u00e1gina de error que muestre su direcci\u00f3n IP y su ID de solicitud (RID).         <\/p>\n<p>                    IP: 74.208.218.121<br \/>\nDESHACERSE: d649f2dcad3c4e8cb8ac000000000001<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su tr\u00e1fico est\u00e1 identificado de forma automatizada (bot). Si es partenaire autorizado, abonado en el mundo, o si desea obtener una autorizaci\u00f3n de acceso a este contenido, merci de contacter: licencia[@]grupoelemonde.fr Al agregar una copia de esta p\u00e1gina de error, incluida su direcci\u00f3n IP y su identificador de solicitud (RID). Su tr\u00e1fico ha sido identificado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":89132,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59,22838],"tags":[],"class_list":["post-89131","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politics","category-white"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=89131"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/89131\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/89132"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=89131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=89131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=89131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}