{"id":64450,"date":"2026-05-17T21:52:05","date_gmt":"2026-05-18T00:52:05","guid":{"rendered":"https:\/\/service.codeus.ca\/index.php\/2026\/05\/17\/elecciones-2026-oea-exhorta-a-evitar-amenazas-y-discursos-de-division-rumbo-a-la-segunda-vuelta\/"},"modified":"2026-05-17T21:52:05","modified_gmt":"2026-05-18T00:52:05","slug":"elecciones-2026-oea-exhorta-a-evitar-amenazas-y-discursos-de-division-rumbo-a-la-segunda-vuelta","status":"publish","type":"post","link":"https:\/\/service.codeus.ca\/index.php\/2026\/05\/17\/elecciones-2026-oea-exhorta-a-evitar-amenazas-y-discursos-de-division-rumbo-a-la-segunda-vuelta\/","title":{"rendered":"Elecciones 2026: OEA exhorta a evitar amenazas y discursos de divisi\u00f3n rumbo a la segunda vuelta"},"content":{"rendered":"<p>La misi\u00f3n de observaci\u00f3n electoral de la Organizaci\u00f3n de los Estados Americanos (OEA) en Per\u00fa exhort\u00f3 este domingo a las autoridades electorales ya los actores pol\u00edticos y sociales a evitar amenazas y discursos que generen divisi\u00f3n social, luego de que el Jurado Nacional de Elecciones (JNE) oficializar\u00e1 los resultados de la primera vuelta presidencial.<\/p>\n<p>La misi\u00f3n de observaci\u00f3n electoral de la Organizaci\u00f3n de los Estados Americanos (OEA) en Per\u00fa exhort\u00f3 este domingo a las autoridades electorales ya los actores pol\u00edticos y sociales a evitar amenazas y discursos que generen divisi\u00f3n social, luego de que el Jurado Nacional de Elecciones (JNE) oficializar\u00e1 los resultados de la primera vuelta presidencial.<\/p>\n<p>LEE: Aritm\u00e9tica en el Senado: Estos son los escenarios de votaci\u00f3n y las bancadas claves para la aceleraci\u00f3n de fuerzas en el CongresoA trav\u00e9s de un comunicado difundido tras la proclamaci\u00f3n de resultados, la delegaci\u00f3n de observadores pidi\u00f3 a los participantes ya las autoridades conducir el proceso electoral. \u201cCon alto sentido de responsabilidad democr\u00e1tica\u201d.<\/p>\n<p>En ese contexto, la misi\u00f3n inst\u00f3 a dejar de lado \u201cconfrontaciones o amenazas, as\u00ed como discursos que generan divisi\u00f3n social\u201dde cara a la segunda vuelta presidencial que disputar\u00e1n la candidata de derecha Keiko Fujimori y el postulante de izquierda Roberto Sanchez.<\/p>\n<p>\u201cLa MOE\/OEA en Per\u00fa hace un llamado especial a las candidaturas contendientes para que las campa\u00f1as se fundamenten en ideas y propuestas claras de gobierno\u201dse\u00f1al\u00f3 el organismo internacional.<\/p>\n<p>La misi\u00f3n tambi\u00e9n salud\u00f3 la proclamaci\u00f3n oficial de los resultados luego de varias semanas marcadas por presiones y amenazas dirigidas a las autoridades electorales por parte del candidato ultraderechista. Rafael L\u00f3pez Aliagaquien denunci\u00f3 un presunto fraude sin presentar pruebas concretas, tras quedar fuera de la segunda vuelta por un estrecho margen de votos.<\/p>\n<p>Asimismo, el grupo de observadores encabezado por el exsecretario general del Banco de Desarrollo de Am\u00e9rica Latina y el Caribe (CAF), V\u00edctor Ricoreconoci\u00f3 a \u201cla ciudadan\u00eda ya los actores pol\u00edticos que guardaron con paciencia y madurez democr\u00e1tica los resultados electorales\u201d.<\/p>\n<p>Tanto la OEA como la Uni\u00f3n Europea (UE)principales misiones internacionales de observaci\u00f3n desplegadas en los c\u00f3mics peruanos, se\u00f1alaron previamente que no encontraron indicios de fraude y consideraron que los resultados del proceso son cre\u00edbles y transparentes.<\/p>\n<p>M\u00c1S: Roberto S\u00e1nchez dispuesto a debatir con Keiko Fujimori: \u201cLlamo a un debate alturado, sobre econom\u00eda, pol\u00edtica, Estado y sociedad\u201dNo obstante, ambas misiones registraron incidencias durante la jornada electoral, entre ellas retrasos en la apertura de centros de votaci\u00f3n en Lima por falta de material electoral. La situaci\u00f3n oblig\u00f3 a realizar las elecciones al d\u00eda siguiente en tres locales que no pudieron abrir el domingo 12 de abril.<\/p>\n<p>La misi\u00f3n de observaci\u00f3n electoral de la OEA inform\u00f3 adem\u00e1s que, al igual que en la primera vuelta, desplegar\u00e1 m\u00e1s de 90 observadores para supervisar la segunda vuelta presidencial en distintas regiones del pa\u00eds y en algunas ciudades del extranjero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La misi\u00f3n de observaci\u00f3n electoral de la Organizaci\u00f3n de los Estados Americanos (OEA) en Per\u00fa exhort\u00f3 este domingo a las autoridades electorales ya los actores pol\u00edticos y sociales a evitar amenazas y discursos que generen divisi\u00f3n social, luego de que el Jurado Nacional de Elecciones (JNE) oficializar\u00e1 los resultados de la primera vuelta presidencial. La [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":64451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1037,419],"tags":[],"class_list":["post-64450","post","type-post","status-publish","format-standard","has-post-thumbnail","category-elecciones","category-peru"],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/64450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/comments?post=64450"}],"version-history":[{"count":0,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts\/64450\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media\/64451"}],"wp:attachment":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/media?parent=64450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories?post=64450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/tags?post=64450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}