{"id":23213,"count":1,"description":"","link":"https:\/\/service.codeus.ca\/index.php\/category\/zoe-bogach\/","name":"Zoe Bogach","slug":"zoe-bogach","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories\/23213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts?categories=23213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}