{"id":22995,"count":1,"description":"","link":"https:\/\/service.codeus.ca\/index.php\/category\/row\/","name":"Row","slug":"row","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories\/22995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts?categories=22995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}