{"id":22920,"count":1,"description":"","link":"https:\/\/service.codeus.ca\/index.php\/category\/boeing-787\/","name":"Boeing 787","slug":"boeing-787","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories\/22920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/service.codeus.ca\/index.php\/wp-json\/wp\/v2\/posts?categories=22920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}